{"id":747,"date":"2025-08-26T03:15:27","date_gmt":"2025-08-26T03:15:27","guid":{"rendered":"https:\/\/sasico.pikathemes.site\/startup\/?page_id=747"},"modified":"2025-10-15T09:15:31","modified_gmt":"2025-10-15T09:15:31","slug":"about-us","status":"publish","type":"page","link":"https:\/\/sasico.pikathemes.site\/startup\/about-us\/","title":{"rendered":"About Us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"747\" class=\"elementor elementor-747\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a70aecd section-padd-bot e-flex e-con-boxed e-con e-parent\" data-id=\"a70aecd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d050b1 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1d050b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLearn about us\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b248966 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b248966\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Fueling Ambition with Strategy &amp; Design<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20127d7 elementor-invisible elementor-widget elementor-widget-sasi-breadcrumbs\" data-id=\"20127d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"sasi-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul id=\"sasi-breadcrumbs\" class=\"sasi-breadcrumbs none-style\"><li><a href=\"https:\/\/sasico.pikathemes.site\/startup\">Home<\/a><\/li><\/ul>    \r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12fdfe2 section-padd e-flex e-con-boxed e-con e-parent\" data-id=\"12fdfe2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b6c4bcd e-con-full e-flex e-con e-child\" data-id=\"b6c4bcd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4a11b16 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"4a11b16\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-373cce3 elementor-widget elementor-widget-sasi-heading\" data-id=\"373cce3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sasi-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"sasi-heading\">\r\n\t        <span class=\"sasi-heading__sub\">Who we are<\/span>\t        <h2 class=\"sasi-heading__title\">We\u2019re a creative startup agency built for bold thinks and early visionaries.<\/h2>\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10ed3bf e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"10ed3bf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8528854 sasi-tab-horizontal sasi-view-icon-default elementor-widget elementor-widget-sasi-button-tabs\" data-id=\"8528854\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sasi-button-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"sasi-btn-tabs dflex flex-wrap flex-row\">\n\t\t\t\t\t\t<a class=\"sasi-btn sasi-btn-outline_2 flex-column \" data-tab=\"tab-1\"> \n\t\t\t\t\t\t\t\t<span class=\"sasi-text\">Our Mission<\/span> \n\t\t\t<\/a>\n\t\t\t\t\t\t<a class=\"sasi-btn sasi-btn-outline_2 flex-column \" data-tab=\"tab-2\"> \n\t\t\t\t\t\t\t\t<span class=\"sasi-text\">Our Vision<\/span> \n\t\t\t<\/a>\n\t\t\t\t\t\t<a class=\"sasi-btn sasi-btn-outline_2 flex-column \" data-tab=\"tab-3\"> \n\t\t\t\t\t\t\t\t<span class=\"sasi-text\">Our Goals<\/span> \n\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t    \n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e40c72 e-con-full e-flex e-con e-child\" data-id=\"6e40c72\" data-element_type=\"container\" data-e-type=\"container\" id=\"tab-1\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9758fd elementor-widget elementor-widget-text-editor\" data-id=\"a9758fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Our mission is to empower startups with innovative design, smart strategy, and scalable solutions. We aim to bridge the gap between vision and execution\u2014helping founders bring bold ideas to life<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13ca20f sasi-view-default elementor-widget elementor-widget-sasi-icon-list\" data-id=\"13ca20f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sasi-icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t        <div class=\"sasi-icon-list-wrapper\">\n\t        \t<ul class=\"unstyle sasi-icon-list-items \">\n\t        \t\t\t        \t\t\t<li class=\"sasi-icon-list-item \">\n\t        \t\t\t\t\n\t\t\t\t\t\t\t<span class=\"sasi-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"12\" viewBox=\"0 0 16 12\" fill=\"#696969\"><path d=\"M13.5938 0.625C13.75 0.46875 14 0.46875 14.125 0.625L15.0312 1.5C15.1562 1.65625 15.1562 1.90625 15.0312 2.03125L5.65625 11.4062C5.5 11.5625 5.28125 11.5625 5.125 11.4062L0.9375 7.25C0.8125 7.09375 0.8125 6.84375 0.9375 6.71875L1.84375 5.8125C1.96875 5.6875 2.21875 5.6875 2.375 5.8125L5.375 8.84375L13.5938 0.625Z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sasi-icon-list-text \">Transforming Complexity Into Clarity<\/span>\n\t\t\t\t\t\t\t\t        \t\t\t<\/li>\n\t        \t\t\t        \t\t\t<li class=\"sasi-icon-list-item \">\n\t        \t\t\t\t\n\t\t\t\t\t\t\t<span class=\"sasi-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"12\" viewBox=\"0 0 16 12\" fill=\"#696969\"><path d=\"M13.5938 0.625C13.75 0.46875 14 0.46875 14.125 0.625L15.0312 1.5C15.1562 1.65625 15.1562 1.90625 15.0312 2.03125L5.65625 11.4062C5.5 11.5625 5.28125 11.5625 5.125 11.4062L0.9375 7.25C0.8125 7.09375 0.8125 6.84375 0.9375 6.71875L1.84375 5.8125C1.96875 5.6875 2.21875 5.6875 2.375 5.8125L5.375 8.84375L13.5938 0.625Z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sasi-icon-list-text \">Unlock Efficiency, Scale Faster, and Work Smarter<\/span>\n\t\t\t\t\t\t\t\t        \t\t\t<\/li>\n\t        \t\t\t        \t\t\t<li class=\"sasi-icon-list-item \">\n\t        \t\t\t\t\n\t\t\t\t\t\t\t<span class=\"sasi-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"12\" viewBox=\"0 0 16 12\" fill=\"#696969\"><path d=\"M13.5938 0.625C13.75 0.46875 14 0.46875 14.125 0.625L15.0312 1.5C15.1562 1.65625 15.1562 1.90625 15.0312 2.03125L5.65625 11.4062C5.5 11.5625 5.28125 11.5625 5.125 11.4062L0.9375 7.25C0.8125 7.09375 0.8125 6.84375 0.9375 6.71875L1.84375 5.8125C1.96875 5.6875 2.21875 5.6875 2.375 5.8125L5.375 8.84375L13.5938 0.625Z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sasi-icon-list-text \">Real Results, Real Growth \u2014 Backed by Powerful Automation<\/span>\n\t\t\t\t\t\t\t\t        \t\t\t<\/li>\n\t        \t\t\t        \t<\/ul>\n\t        <\/div>\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-420396b e-con-full e-flex e-con e-child\" data-id=\"420396b\" data-element_type=\"container\" data-e-type=\"container\" id=\"tab-2\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9f96bb elementor-widget elementor-widget-text-editor\" data-id=\"f9f96bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tTo create a world where startups thrive through seamless design, intelligent technology, and sustainable growth. We envision an ecosystem where bold innovation turns into lasting impact.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fda2f88 sasi-view-default elementor-widget elementor-widget-sasi-icon-list\" data-id=\"fda2f88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sasi-icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t        <div class=\"sasi-icon-list-wrapper\">\n\t        \t<ul class=\"unstyle sasi-icon-list-items \">\n\t        \t\t\t        \t\t\t<li class=\"sasi-icon-list-item \">\n\t        \t\t\t\t\n\t\t\t\t\t\t\t<span class=\"sasi-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"12\" viewBox=\"0 0 16 12\" fill=\"#696969\"><path d=\"M13.5938 0.625C13.75 0.46875 14 0.46875 14.125 0.625L15.0312 1.5C15.1562 1.65625 15.1562 1.90625 15.0312 2.03125L5.65625 11.4062C5.5 11.5625 5.28125 11.5625 5.125 11.4062L0.9375 7.25C0.8125 7.09375 0.8125 6.84375 0.9375 6.71875L1.84375 5.8125C1.96875 5.6875 2.21875 5.6875 2.375 5.8125L5.375 8.84375L13.5938 0.625Z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sasi-icon-list-text \">Designing the Future with Purpose<\/span>\n\t\t\t\t\t\t\t\t        \t\t\t<\/li>\n\t        \t\t\t        \t\t\t<li class=\"sasi-icon-list-item \">\n\t        \t\t\t\t\n\t\t\t\t\t\t\t<span class=\"sasi-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"12\" viewBox=\"0 0 16 12\" fill=\"#696969\"><path d=\"M13.5938 0.625C13.75 0.46875 14 0.46875 14.125 0.625L15.0312 1.5C15.1562 1.65625 15.1562 1.90625 15.0312 2.03125L5.65625 11.4062C5.5 11.5625 5.28125 11.5625 5.125 11.4062L0.9375 7.25C0.8125 7.09375 0.8125 6.84375 0.9375 6.71875L1.84375 5.8125C1.96875 5.6875 2.21875 5.6875 2.375 5.8125L5.375 8.84375L13.5938 0.625Z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sasi-icon-list-text \">Building Sustainable Success Through Innovation<\/span>\n\t\t\t\t\t\t\t\t        \t\t\t<\/li>\n\t        \t\t\t        \t\t\t<li class=\"sasi-icon-list-item \">\n\t        \t\t\t\t\n\t\t\t\t\t\t\t<span class=\"sasi-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"12\" viewBox=\"0 0 16 12\" fill=\"#696969\"><path d=\"M13.5938 0.625C13.75 0.46875 14 0.46875 14.125 0.625L15.0312 1.5C15.1562 1.65625 15.1562 1.90625 15.0312 2.03125L5.65625 11.4062C5.5 11.5625 5.28125 11.5625 5.125 11.4062L0.9375 7.25C0.8125 7.09375 0.8125 6.84375 0.9375 6.71875L1.84375 5.8125C1.96875 5.6875 2.21875 5.6875 2.375 5.8125L5.375 8.84375L13.5938 0.625Z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sasi-icon-list-text \">Lasting Impact \u2014 Driven by Creativity and Technology<\/span>\n\t\t\t\t\t\t\t\t        \t\t\t<\/li>\n\t        \t\t\t        \t<\/ul>\n\t        <\/div>\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-759b388 e-con-full e-flex e-con e-child\" data-id=\"759b388\" data-element_type=\"container\" data-e-type=\"container\" id=\"tab-3\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58ad2dc elementor-widget elementor-widget-text-editor\" data-id=\"58ad2dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>We strive to support founders at every stage with clear direction, agile solutions, and measurable growth. Our goal is to turn ambition into achievement\u2014building startups that last.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4991c6c sasi-view-default elementor-widget elementor-widget-sasi-icon-list\" data-id=\"4991c6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sasi-icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t        <div class=\"sasi-icon-list-wrapper\">\n\t        \t<ul class=\"unstyle sasi-icon-list-items \">\n\t        \t\t\t        \t\t\t<li class=\"sasi-icon-list-item \">\n\t        \t\t\t\t\n\t\t\t\t\t\t\t<span class=\"sasi-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"12\" viewBox=\"0 0 16 12\" fill=\"#696969\"><path d=\"M13.5938 0.625C13.75 0.46875 14 0.46875 14.125 0.625L15.0312 1.5C15.1562 1.65625 15.1562 1.90625 15.0312 2.03125L5.65625 11.4062C5.5 11.5625 5.28125 11.5625 5.125 11.4062L0.9375 7.25C0.8125 7.09375 0.8125 6.84375 0.9375 6.71875L1.84375 5.8125C1.96875 5.6875 2.21875 5.6875 2.375 5.8125L5.375 8.84375L13.5938 0.625Z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sasi-icon-list-text \">Guiding Startups from Idea to Impact<\/span>\n\t\t\t\t\t\t\t\t        \t\t\t<\/li>\n\t        \t\t\t        \t\t\t<li class=\"sasi-icon-list-item \">\n\t        \t\t\t\t\n\t\t\t\t\t\t\t<span class=\"sasi-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"12\" viewBox=\"0 0 16 12\" fill=\"#696969\"><path d=\"M13.5938 0.625C13.75 0.46875 14 0.46875 14.125 0.625L15.0312 1.5C15.1562 1.65625 15.1562 1.90625 15.0312 2.03125L5.65625 11.4062C5.5 11.5625 5.28125 11.5625 5.125 11.4062L0.9375 7.25C0.8125 7.09375 0.8125 6.84375 0.9375 6.71875L1.84375 5.8125C1.96875 5.6875 2.21875 5.6875 2.375 5.8125L5.375 8.84375L13.5938 0.625Z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sasi-icon-list-text \">Driving Sustainable Growth with Smart Execution<\/span>\n\t\t\t\t\t\t\t\t        \t\t\t<\/li>\n\t        \t\t\t        \t\t\t<li class=\"sasi-icon-list-item \">\n\t        \t\t\t\t\n\t\t\t\t\t\t\t<span class=\"sasi-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"12\" viewBox=\"0 0 16 12\" fill=\"#696969\"><path d=\"M13.5938 0.625C13.75 0.46875 14 0.46875 14.125 0.625L15.0312 1.5C15.1562 1.65625 15.1562 1.90625 15.0312 2.03125L5.65625 11.4062C5.5 11.5625 5.28125 11.5625 5.125 11.4062L0.9375 7.25C0.8125 7.09375 0.8125 6.84375 0.9375 6.71875L1.84375 5.8125C1.96875 5.6875 2.21875 5.6875 2.375 5.8125L5.375 8.84375L13.5938 0.625Z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"sasi-icon-list-text \">From Vision to Value \u2014 Every Step of the Journey<\/span>\n\t\t\t\t\t\t\t\t        \t\t\t<\/li>\n\t        \t\t\t        \t<\/ul>\n\t        <\/div>\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e42c472 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"e42c472\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1290\" height=\"600\" src=\"https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/about-image1.webp\" class=\"attachment-full size-full wp-image-803\" alt=\"\" srcset=\"https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/about-image1.webp 1290w, https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/about-image1-300x140.webp 300w, https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/about-image1-1024x476.webp 1024w, https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/about-image1-768x357.webp 768w\" sizes=\"(max-width: 1290px) 100vw, 1290px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64a11c9 e-con-full e-grid e-con e-child\" data-id=\"64a11c9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5aaa1f elementor-invisible elementor-widget elementor-widget-counter\" data-id=\"b5aaa1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Global happy Users<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"380\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a36dcb7 elementor-invisible elementor-widget elementor-widget-counter\" data-id=\"a36dcb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Expert Team Member<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"68\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2f4f59 elementor-invisible elementor-widget elementor-widget-counter\" data-id=\"e2f4f59\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Globally Awarded<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"238\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4af4ea0 elementor-invisible elementor-widget elementor-widget-counter\" data-id=\"4af4ea0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Project Complete<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"863\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b03aef section-padd e-flex e-con-boxed e-con e-parent\" data-id=\"9b03aef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b398baf elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-sasi-heading\" data-id=\"b398baf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"sasi-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"sasi-heading\">\r\n\t        <span class=\"sasi-heading__sub\">Meet Our Team<\/span>\t        <h2 class=\"sasi-heading__title\">We\u2019re 50+ individuals and professional members<\/h2>\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42d1ad4 e-con-full e-grid e-con e-child\" data-id=\"42d1ad4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5c98ce elementor-invisible elementor-widget elementor-widget-sasi-team\" data-id=\"a5c98ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"sasi-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"sasi-team\">\n\t\t\t<div class=\"sasi-team__thumb\">\n\t\t\t\t<a href=\"https:\/\/sasico.pikathemes.site\/our-team\/single-team\/\"><img decoding=\"async\" width=\"615\" height=\"705\" src=\"https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/member9.webp\" class=\"attachment-full size-full wp-image-805\" alt=\"\" srcset=\"https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/member9.webp 615w, https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/member9-262x300.webp 262w\" sizes=\"(max-width: 615px) 100vw, 615px\" \/><\/a>\t\t\t\t\t\t\t\t<div class=\"sasi-team__social dflex flex-column\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"sasi-social-icons__item dflex justify-content-center align-items-center facebook elementor-repeater-item-a99ffb3\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"sasi-icon\">\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-facebook-f\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M279.14 288l14.22-92.66h-88.91v-60.13c0-25.35 12.42-50.06 52.24-50.06h40.42V6.26S260.43 0 225.36 0c-73.22 0-121.08 44.38-121.08 124.72v70.62H22.89V288h81.39v224h100.17V288z\"><\/path><\/svg><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"sasi-social-icons__item dflex justify-content-center align-items-center instagram elementor-repeater-item-fc101e2\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"sasi-icon\">\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-x-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"><\/path><\/svg><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"sasi-social-icons__item dflex justify-content-center align-items-center youtube elementor-repeater-item-12f2f28\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"sasi-icon\">\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-linkedin-in\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"sasi-team__info\">\n\t\t\t\t<h5 class=\"sasi-team__name\"><a href=\"https:\/\/sasico.pikathemes.site\/our-team\/single-team\/\">Walter D. Gonzales<\/a><\/h5>\t\t\t\t<span class=\"sasi-team__job\">CEO & Founder<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t        \n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-500abcb elementor-invisible elementor-widget elementor-widget-sasi-team\" data-id=\"500abcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"sasi-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"sasi-team\">\n\t\t\t<div class=\"sasi-team__thumb\">\n\t\t\t\t<a href=\"https:\/\/sasico.pikathemes.site\/our-team\/single-team\/\"><img decoding=\"async\" width=\"615\" height=\"705\" src=\"https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/member2.webp\" class=\"attachment-full size-full wp-image-806\" alt=\"\" srcset=\"https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/member2.webp 615w, https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/member2-262x300.webp 262w\" sizes=\"(max-width: 615px) 100vw, 615px\" \/><\/a>\t\t\t\t\t\t\t\t<div class=\"sasi-team__social dflex flex-column\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"sasi-social-icons__item dflex justify-content-center align-items-center facebook elementor-repeater-item-a99ffb3\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"sasi-icon\">\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-facebook-f\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M279.14 288l14.22-92.66h-88.91v-60.13c0-25.35 12.42-50.06 52.24-50.06h40.42V6.26S260.43 0 225.36 0c-73.22 0-121.08 44.38-121.08 124.72v70.62H22.89V288h81.39v224h100.17V288z\"><\/path><\/svg><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"sasi-social-icons__item dflex justify-content-center align-items-center instagram elementor-repeater-item-fc101e2\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"sasi-icon\">\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-x-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"><\/path><\/svg><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"sasi-social-icons__item dflex justify-content-center align-items-center youtube elementor-repeater-item-12f2f28\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"sasi-icon\">\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-linkedin-in\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"sasi-team__info\">\n\t\t\t\t<h5 class=\"sasi-team__name\"><a href=\"https:\/\/sasico.pikathemes.site\/our-team\/single-team\/\">Arnold T. Madden<\/a><\/h5>\t\t\t\t<span class=\"sasi-team__job\">UX UI Designer<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t        \n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce1c9aa elementor-invisible elementor-widget elementor-widget-sasi-team\" data-id=\"ce1c9aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"sasi-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"sasi-team\">\n\t\t\t<div class=\"sasi-team__thumb\">\n\t\t\t\t<a href=\"https:\/\/sasico.pikathemes.site\/our-team\/single-team\/\"><img loading=\"lazy\" decoding=\"async\" width=\"615\" height=\"705\" src=\"https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/member3.webp\" class=\"attachment-full size-full wp-image-807\" alt=\"\" srcset=\"https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/member3.webp 615w, https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/member3-262x300.webp 262w\" sizes=\"(max-width: 615px) 100vw, 615px\" \/><\/a>\t\t\t\t\t\t\t\t<div class=\"sasi-team__social dflex flex-column\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"sasi-social-icons__item dflex justify-content-center align-items-center facebook elementor-repeater-item-a99ffb3\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"sasi-icon\">\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-facebook-f\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M279.14 288l14.22-92.66h-88.91v-60.13c0-25.35 12.42-50.06 52.24-50.06h40.42V6.26S260.43 0 225.36 0c-73.22 0-121.08 44.38-121.08 124.72v70.62H22.89V288h81.39v224h100.17V288z\"><\/path><\/svg><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"sasi-social-icons__item dflex justify-content-center align-items-center instagram elementor-repeater-item-fc101e2\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"sasi-icon\">\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-x-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"><\/path><\/svg><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"sasi-social-icons__item dflex justify-content-center align-items-center youtube elementor-repeater-item-12f2f28\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"sasi-icon\">\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-linkedin-in\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"sasi-team__info\">\n\t\t\t\t<h5 class=\"sasi-team__name\"><a href=\"https:\/\/sasico.pikathemes.site\/our-team\/single-team\/\">Paul C. Lattimore<\/a><\/h5>\t\t\t\t<span class=\"sasi-team__job\">Digital Marketer<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t        \n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b8feab elementor-invisible elementor-widget elementor-widget-sasi-team\" data-id=\"1b8feab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"sasi-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"sasi-team\">\n\t\t\t<div class=\"sasi-team__thumb\">\n\t\t\t\t<a href=\"https:\/\/sasico.pikathemes.site\/our-team\/single-team\/\"><img loading=\"lazy\" decoding=\"async\" width=\"615\" height=\"705\" src=\"https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/member4.webp\" class=\"attachment-full size-full wp-image-808\" alt=\"\" srcset=\"https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/member4.webp 615w, https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/member4-262x300.webp 262w\" sizes=\"(max-width: 615px) 100vw, 615px\" \/><\/a>\t\t\t\t\t\t\t\t<div class=\"sasi-team__social dflex flex-column\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"sasi-social-icons__item dflex justify-content-center align-items-center facebook elementor-repeater-item-a99ffb3\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"sasi-icon\">\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-facebook-f\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M279.14 288l14.22-92.66h-88.91v-60.13c0-25.35 12.42-50.06 52.24-50.06h40.42V6.26S260.43 0 225.36 0c-73.22 0-121.08 44.38-121.08 124.72v70.62H22.89V288h81.39v224h100.17V288z\"><\/path><\/svg><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"sasi-social-icons__item dflex justify-content-center align-items-center instagram elementor-repeater-item-fc101e2\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"sasi-icon\">\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-x-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"><\/path><\/svg><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"sasi-social-icons__item dflex justify-content-center align-items-center youtube elementor-repeater-item-12f2f28\" target=\"_blank\">\n\t\t\t\t\t\t\t\t<span class=\"sasi-icon\">\t\t\t\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-linkedin-in\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg><\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"sasi-team__info\">\n\t\t\t\t<h5 class=\"sasi-team__name\"><a href=\"https:\/\/sasico.pikathemes.site\/our-team\/single-team\/\">Jimmy J. Johnson<\/a><\/h5>\t\t\t\t<span class=\"sasi-team__job\">Web Developer<\/span>\t\t\t<\/div>\n\t\t<\/div>\n\t        \n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-076f52a section-padd e-flex e-con-boxed e-con e-parent\" data-id=\"076f52a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6d7f22 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-sasi-heading\" data-id=\"a6d7f22\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"sasi-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"sasi-heading\">\r\n\t        <span class=\"sasi-heading__sub\">Working Approach<\/span>\t        <h2 class=\"sasi-heading__title\">A Strategic approach to every project Our method your momentum<\/h2>\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-43134d1 e-con-full e-flex e-con e-child\" data-id=\"43134d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-89db17b e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"89db17b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61464d0 elementor-widget elementor-widget-image\" data-id=\"61464d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"945\" height=\"713\" src=\"https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/about-image2.webp\" class=\"attachment-full size-full wp-image-819\" alt=\"\" srcset=\"https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/about-image2.webp 945w, https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/about-image2-300x226.webp 300w, https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/about-image2-768x579.webp 768w\" sizes=\"(max-width: 945px) 100vw, 945px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-303a5ea e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"303a5ea\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3a4806 style-2 elementor-widget elementor-widget-sasi-accordions\" data-id=\"d3a4806\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sasi-accordions.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"sasi-accordions-wrapper one-expand has-distance\">\n\t\t\t\t\t\t<div class=\"sasi-acc-item\">\n\t\t\t\t\n\t\t\t\t<h2 class=\"sasi-acc-item__title\" data-tab=\"1\" data-default=\"yes\" >\n\t\t\t\t\t<span>(01)<\/span> Problem Discover & Define\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t<div class=\"sasi-acc-item__content\">\n\t\t\t\t\t<div class=\"acc__content-inner\"><p>We start by understanding your vision, market, and users. Through research and strategy sessions define clear goals, pain points, and opportunities.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"sasi-acc-item\">\n\t\t\t\t\n\t\t\t\t<h2 class=\"sasi-acc-item__title\" data-tab=\"2\" data-default=\"\" >\n\t\t\t\t\t<span>(02)<\/span> Design system & develop\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t<div class=\"sasi-acc-item__content\">\n\t\t\t\t\t<div class=\"acc__content-inner\"><p>We craft intuitive design systems that scale with your business. From components to guidelines, every detail, efficiency, and a seamless user experience.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"sasi-acc-item\">\n\t\t\t\t\n\t\t\t\t<h2 class=\"sasi-acc-item__title\" data-tab=\"3\" data-default=\"\" >\n\t\t\t\t\t<span>(03)<\/span> Design implementation\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t<div class=\"sasi-acc-item__content\">\n\t\t\t\t\t<div class=\"acc__content-inner\"><p>We turn concepts into seamless interfaces, ensuring every element stays consistent, functional, and ready to scale across platforms.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"sasi-acc-item\">\n\t\t\t\t\n\t\t\t\t<h2 class=\"sasi-acc-item__title\" data-tab=\"4\" data-default=\"\" >\n\t\t\t\t\t<span>(04)<\/span> Optimize & Automate\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t<div class=\"sasi-acc-item__content\">\n\t\t\t\t\t<div class=\"acc__content-inner\"><p>We refine workflows, enhance performance, and integrate smart automation. This ensures faster processes and scalable growth for your business.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t    <\/div>\n\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1953a07 section-padd e-flex e-con-boxed e-con e-parent\" data-id=\"1953a07\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fe0003 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-sasi-heading\" data-id=\"7fe0003\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"sasi-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"sasi-heading\">\r\n\t        <span class=\"sasi-heading__sub\">Services and solutions<\/span>\t        <h2 class=\"sasi-heading__title\">Empowering you through expert services<\/h2>\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c188ed e-con-full e-flex e-con e-child\" data-id=\"6c188ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3e20485 e-con-full e-flex e-con e-child\" data-id=\"3e20485\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f04adc9 e-con-full e-grid elementor-invisible e-con e-child\" data-id=\"f04adc9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21895ec sasi-icon-align-left sasi-view-icon-default sasi-position-top elementor-widget elementor-widget-sasi-iconbox\" data-id=\"21895ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sasi-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"sasi-icon-box\">\n\t\t\t\t\t\t<div class=\"sasi-icon sasi-icon-box__icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"34\" height=\"30\" viewBox=\"0 0 34 30\" fill=\"none\"><path d=\"M29.2831 22.1106C27.4457 22.1106 25.898 23.3733 25.4615 25.0764H24.6921C24.2702 25.0764 23.9272 24.7334 23.9272 24.3116V19.5608H26.9323C30.4036 19.5608 33.2276 16.7368 33.2276 13.2655C33.2276 9.79424 30.4036 6.97017 26.9323 6.97017C26.621 6.97017 26.3112 6.99324 26.005 7.03862C24.8062 2.90443 21.0074 0 16.6138 0C12.2203 0 8.4215 2.90443 7.22266 7.03862C6.91643 6.99299 6.60664 6.97017 6.29534 6.97017C2.82407 6.97017 0 9.79424 0 13.2653C0 16.7365 2.82407 19.5606 6.29534 19.5606H9.30041V24.3116C9.30041 24.7331 8.95741 25.0764 8.53558 25.0764H7.76618C7.32964 23.3733 5.78198 22.1106 3.94457 22.1106C1.76948 22.1106 0 23.8803 0 26.0554C0 28.2305 1.76948 30 3.94457 30C5.78198 30 7.32964 28.7375 7.76618 27.0342H8.53558C10.0368 27.0342 11.2582 25.8128 11.2582 24.3116V19.5608H15.6348V22.2338C13.9317 22.6704 12.6693 24.2183 12.6693 26.0554C12.6693 28.2305 14.4387 30 16.6138 30C18.7889 30 20.5584 28.2305 20.5584 26.0554C20.5584 24.2183 19.2957 22.6704 17.5929 22.2338V19.5608H21.9694V24.3116C21.9694 25.8128 23.1908 27.0342 24.6921 27.0342H25.4615C25.898 28.7375 27.4457 30 29.2831 30C31.4582 30 33.2276 28.2305 33.2276 26.0554C33.2276 23.8803 31.4582 22.1106 29.2831 22.1106ZM3.94457 28.0422C2.84916 28.0422 1.95783 27.1508 1.95783 26.0554C1.95783 24.9598 2.84916 24.0687 3.94457 24.0687C5.04022 24.0687 5.9313 24.9598 5.9313 26.0554C5.9313 27.1508 5.04022 28.0422 3.94457 28.0422ZM18.6006 26.0554C18.6006 27.1508 17.7092 28.0422 16.6138 28.0422C15.5184 28.0422 14.6271 27.1508 14.6271 26.0554C14.6271 24.9598 15.5184 24.0687 16.6138 24.0687C17.7092 24.0687 18.6006 24.9598 18.6006 26.0554ZM1.95783 13.2653C1.95783 10.8737 3.9035 8.928 6.29534 8.928C6.75494 8.928 7.20973 9.00051 7.64678 9.14374C7.916 9.23196 8.21007 9.19926 8.45344 9.054C8.69655 8.90874 8.86488 8.66537 8.91508 8.38651C9.58433 4.66148 12.8221 1.95783 16.6138 1.95783C20.4055 1.95783 23.6433 4.66148 24.3126 8.38651C24.3628 8.66537 24.5311 8.90874 24.7742 9.054C25.0173 9.19926 25.3116 9.23196 25.5809 9.14374C26.0179 9.00051 26.4727 8.928 26.9323 8.928C29.3239 8.928 31.2698 10.8737 31.2698 13.2653C31.2698 15.6571 29.3242 17.6028 26.9323 17.6028H6.29534C3.9035 17.6028 1.95783 15.6571 1.95783 13.2653ZM29.2831 28.0422C28.1874 28.0422 27.2964 27.1508 27.2964 26.0554C27.2964 24.9598 28.1874 24.0684 29.2831 24.0684C30.3785 24.0684 31.2698 24.9598 31.2698 26.0554C31.2698 27.1508 30.3785 28.0422 29.2831 28.0422Z\" fill=\"#3A6EF2\"><\/path><\/svg>\t        <\/div>\n\t        \t        <div class=\"sasi-icon-box__content\">\n\t        \t<h4 class=\"icon-box-title\">Data-Driven Insights<\/h4>\t\t\t\t<div class=\"icon-box-des\">Gain a deeper understanding of your business insights.<\/div>\t\t\t\t\t\t\t<\/div>\t\n\t    <\/div>\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f7441a sasi-icon-align-left sasi-view-icon-default sasi-position-top elementor-widget elementor-widget-sasi-iconbox\" data-id=\"9f7441a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sasi-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"sasi-icon-box\">\n\t\t\t\t\t\t<div class=\"sasi-icon sasi-icon-box__icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><g clip-path=\"url(#clip0_6034_17862)\"><path d=\"M38.8278 40H1.17187C0.524683 40 0 39.4753 0 38.8281C0 38.1809 0.524683 37.6562 1.17187 37.6562H38.8278C39.475 37.6562 39.9997 38.1809 39.9997 38.8281C39.9997 39.4753 39.475 40 38.8278 40Z\" fill=\"#3A6EF2\"><\/path><path d=\"M8.2812 39.9999H3.59374C2.94656 39.9999 2.42188 39.4752 2.42188 38.828V30.2344C2.42188 29.1574 3.29804 28.2812 4.37498 28.2812H7.49996C8.5769 28.2812 9.45307 29.1574 9.45307 30.2344V38.828C9.45307 39.4752 8.92839 39.9999 8.2812 39.9999ZM4.76561 37.6562H7.10934V30.625H4.76561V37.6562Z\" fill=\"#3A6EF2\"><\/path><path d=\"M17.6562 39.9999H12.9687C12.3216 39.9999 11.7969 39.4752 11.7969 38.828V27.4219C11.7969 26.3449 12.673 25.4688 13.75 25.4688H16.875C17.9519 25.4688 18.8281 26.3449 18.8281 27.4219V38.828C18.8281 39.4752 18.3034 39.9999 17.6562 39.9999ZM14.1406 37.6562H16.4843V27.8125H14.1406V37.6562Z\" fill=\"#3A6EF2\"><\/path><path d=\"M27.031 39.9999H22.3435C21.6963 39.9999 21.1716 39.4752 21.1716 38.828V23.125C21.1716 22.048 22.0478 21.1719 23.1247 21.1719H26.2497C27.3267 21.1719 28.2028 22.048 28.2028 23.125V38.828C28.2028 39.4752 27.6781 39.9999 27.031 39.9999ZM23.5154 37.6561H25.8591V23.5156H23.5154V37.6561Z\" fill=\"#3A6EF2\"><\/path><path d=\"M36.406 39.9998H31.7185C31.0713 39.9998 30.5466 39.4751 30.5466 38.8279V15.3125C30.5466 14.2355 31.4228 13.3594 32.4997 13.3594H35.6247C36.7017 13.3594 37.5778 14.2355 37.5778 15.3125V38.8279C37.5778 39.4751 37.0531 39.9998 36.406 39.9998ZM32.8904 37.6561H35.2341V15.7031H32.8904V37.6561Z\" fill=\"#3A6EF2\"><\/path><path d=\"M1.17187 25.1799C0.524683 25.1799 0 24.6552 0 24.008C0 23.3608 0.524683 22.8361 1.17187 22.8361C8.06291 22.8361 15.5658 20.3268 22.2983 15.7703C28.4921 11.5786 33.4276 6.08328 35.8391 0.693557C36.1035 0.10278 36.7967 -0.161905 37.3874 0.102546C37.9781 0.366841 38.2427 1.06004 37.9784 1.65082C35.3936 7.42788 30.1572 13.2817 23.612 17.7113C16.4957 22.5275 8.52626 25.1799 1.17187 25.1799Z\" fill=\"#3A6EF2\"><\/path><path d=\"M38.8272 9.50595C38.3097 9.50595 37.8363 9.16064 37.696 8.63705L36.0804 2.60733L30.0506 4.22302C29.4253 4.39068 28.7829 4.01959 28.6154 3.39444C28.4479 2.76928 28.8189 2.12671 29.444 1.95921L36.6057 0.0402427C37.2311 -0.127334 37.8734 0.243757 38.0409 0.86883L39.9599 8.03049C40.1274 8.65564 39.7564 9.29822 39.1313 9.46572C39.0296 9.4929 38.9276 9.50595 38.8272 9.50595Z\" fill=\"#3A6EF2\"><\/path><\/g><defs><clipPath id=\"clip0_6034_17862\"><rect width=\"40\" height=\"40\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t        <\/div>\n\t        \t        <div class=\"sasi-icon-box__content\">\n\t        \t<h4 class=\"icon-box-title\">Scalable Approach<\/h4>\t\t\t\t<div class=\"icon-box-des\">Scalable approach ensures the\nyour solutions grow business.<\/div>\t\t\t\t\t\t\t<\/div>\t\n\t    <\/div>\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c172eff sasi-icon-align-left sasi-view-icon-default sasi-position-top elementor-widget elementor-widget-sasi-iconbox\" data-id=\"c172eff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sasi-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"sasi-icon-box\">\n\t\t\t\t\t\t<div class=\"sasi-icon sasi-icon-box__icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"41\" height=\"41\" viewBox=\"0 0 41 41\" fill=\"none\"><path d=\"M38.7619 30.3863L29.7452 21.3562C29.5957 21.2141 29.3972 21.1348 29.1909 21.1348C28.9846 21.1348 28.7861 21.2141 28.6366 21.3562L26.8485 23.1443L24.7429 21.0433L29.8257 15.9337C31.9491 15.8219 34.7788 15.8309 34.904 15.813C35.4315 15.7325 36.4418 14.9189 39.8616 10.3189C39.9566 10.1889 40.0096 10.0329 40.0136 9.87191V7.80214C40.0133 7.66435 39.9768 7.52907 39.9077 7.40982C39.8387 7.29057 39.7395 7.19155 39.6202 7.12265C39.5011 7.05226 39.3652 7.01512 39.2268 7.01512C39.0884 7.01512 38.9526 7.05226 38.8334 7.12265L35.2169 9.26841C34.9085 9.36676 33.554 9.68416 32.3961 8.0346C31.1444 6.24647 31.7032 5.38816 32.4945 4.71314C33.676 3.86904 34.9027 3.09004 36.1691 2.37962C36.2834 2.31284 36.3793 2.21858 36.448 2.10539C36.5167 1.99221 36.556 1.86367 36.5625 1.73142C36.5675 1.59937 36.539 1.46821 36.4795 1.35017C36.4201 1.23213 36.3318 1.13107 36.2228 1.0564C36.111 0.980407 33.3886 -0.839021 28.7126 0.971466C25.1006 2.36621 24.5954 4.20352 24.5507 4.40916L23.7818 9.84062L18.6677 14.9592L14.099 10.3771C14.2971 9.87905 14.4002 9.34837 14.403 8.81244C14.4041 8.25584 14.2948 7.70456 14.0815 7.19046C13.8682 6.67636 13.5551 6.20965 13.1603 5.81731C13.1229 5.77808 13.0809 5.74355 13.0351 5.71449L5.29695 0.680894C5.14743 0.581943 4.96832 0.537683 4.78992 0.555604C4.61152 0.573526 4.4448 0.652527 4.31795 0.779241L1.10377 3.99341C0.977059 4.12026 0.898057 4.28699 0.880136 4.46539C0.862215 4.64379 0.906474 4.8229 1.00543 4.97242L6.05244 12.6972C6.08285 12.7419 6.11727 12.7838 6.15526 12.8223C6.54668 13.2168 7.01269 13.5294 7.52614 13.742C8.03958 13.9546 8.5902 14.0629 9.14591 14.0606C9.68323 14.0615 10.2158 13.9598 10.715 13.7611L15.2837 18.3432L9.68682 23.9401L4.32242 24.7H4.2643C4.05867 24.7492 2.22583 25.2499 0.826612 28.8664C-0.961523 33.5424 0.826612 36.2603 0.916019 36.3765C0.989926 36.4845 1.08946 36.5725 1.2057 36.6326C1.32194 36.6926 1.45127 36.7229 1.5821 36.7208C1.71363 36.7161 1.84178 36.6779 1.95443 36.6098C2.06707 36.5418 2.16049 36.4461 2.22583 36.3318C2.93683 35.0658 3.71581 33.8391 4.55935 32.6572C5.23437 31.866 6.10608 31.3161 7.88528 32.5544C9.5393 33.7212 9.22638 35.0846 9.11909 35.3752L6.97333 38.9917C6.9018 39.11 6.86312 39.2453 6.86126 39.3836C6.85939 39.5218 6.89442 39.6581 6.96273 39.7783C7.03103 39.8985 7.13016 39.9984 7.24988 40.0675C7.36961 40.1367 7.50561 40.1727 7.64388 40.1719H9.71364C9.87558 40.169 10.0323 40.1141 10.1607 40.0154C14.8545 36.5464 15.6011 35.5451 15.6637 35.0399C15.6637 34.9326 15.6637 32.1029 15.7754 29.984L21.3589 24.4273L23.4868 26.5239L21.6986 28.3121C21.5523 28.4594 21.4702 28.6587 21.4702 28.8664C21.4702 29.0741 21.5523 29.2733 21.6986 29.4207L30.7287 38.4463C31.7429 39.4591 33.1176 40.0279 34.5508 40.0279C35.9841 40.0279 37.3588 39.4591 38.373 38.4463L38.7798 38.0395C39.2829 37.5382 39.682 36.9426 39.9544 36.2867C40.2268 35.6308 40.367 34.9276 40.367 34.2174C40.367 33.5072 40.2268 32.804 39.9544 32.1481C39.682 31.4922 39.2829 30.8965 38.7798 30.3952L38.7619 30.3863ZM25.0737 10.766C25.1924 10.644 25.2691 10.4875 25.2928 10.3189L26.084 4.75784C26.1332 4.63267 26.6562 3.46591 29.2758 2.45115C30.7559 1.80721 32.3899 1.60238 33.9831 1.86106C33.1134 2.36431 32.2758 2.92119 31.4753 3.5285C29.325 5.37028 30.0939 7.48475 31.1132 8.93761C32.7091 11.2041 34.9085 11.0923 35.8428 10.7257C35.8785 10.7257 38.449 9.19242 38.449 9.19242V9.63945C36.9827 11.6064 35.2169 13.7924 34.6179 14.2752C33.5897 14.2215 30.7287 14.3601 29.4457 14.4317C29.2519 14.4409 29.0686 14.5222 28.9316 14.6596L23.6388 19.9257L22.2976 18.5846L27.4028 13.4571C27.486 13.3873 27.5537 13.3009 27.6017 13.2035C27.6497 13.106 27.6769 12.9997 27.6815 12.8912C27.6862 12.7826 27.6681 12.6744 27.6286 12.5732C27.5891 12.472 27.529 12.3802 27.452 12.3035C27.375 12.2269 27.283 12.1671 27.1816 12.128C27.0803 12.0889 26.9719 12.0713 26.8634 12.0764C26.7549 12.0814 26.6487 12.109 26.5514 12.1574C26.4542 12.2058 26.3681 12.2739 26.2986 12.3574L21.1801 17.4715L19.7764 16.0633L25.0737 10.766ZM9.1325 12.496C8.45247 12.4993 7.79744 12.2399 7.30413 11.7718L2.65945 4.65055L4.97509 2.33492L12.0963 6.99301C12.57 7.49962 12.829 8.17001 12.819 8.86348C12.809 9.55695 12.5308 10.2196 12.0427 10.7123L11.019 11.736C10.7715 11.9839 10.4774 12.1802 10.1536 12.3137C9.82979 12.4473 9.48274 12.5153 9.1325 12.5139V12.496ZM14.4701 29.0944C14.3322 29.2292 14.2507 29.4113 14.2421 29.604C14.1706 30.8914 14.032 33.748 14.0901 34.7762C13.6073 35.3752 11.4079 37.1454 9.44989 38.6117H9.00286C9.00286 38.6117 10.5228 36.0502 10.5496 36.0055C10.9296 35.0667 11.0458 32.8763 8.76146 31.2759C7.3086 30.2567 5.18519 29.4878 3.34788 31.638C2.74107 32.4389 2.1842 33.2764 1.68045 34.1458C1.42138 32.5522 1.62783 30.9177 2.275 29.4386C3.29424 26.7966 4.46547 26.3093 4.5817 26.2423L10.1651 25.451C10.3342 25.4293 10.4914 25.3523 10.6122 25.232L16.3879 19.4474L17.796 20.8511L12.15 26.5016C12.0766 26.5736 12.0183 26.6595 11.9785 26.7543C11.9387 26.8491 11.9182 26.9508 11.9182 27.0537C11.9182 27.1565 11.9387 27.2582 11.9785 27.353C12.0183 27.4478 12.0766 27.5337 12.15 27.6057C12.222 27.6791 12.3079 27.7374 12.4027 27.7772C12.4975 27.817 12.5993 27.8375 12.7021 27.8375C12.8049 27.8375 12.9067 27.817 13.0015 27.7772C13.0962 27.7374 13.1822 27.6791 13.2542 27.6057L18.9002 21.9597L20.2413 23.3008L14.4701 29.0944ZM12.0472 12.8939L12.1276 12.8223L13.1469 11.8031L13.2184 11.7226L25.7353 24.2396L24.5641 25.4108L12.0472 12.8939ZM37.6577 36.9443L37.2509 37.3555C36.5288 38.074 35.5516 38.4774 34.533 38.4774C33.5143 38.4774 32.5371 38.074 31.815 37.3555L23.3437 28.8619L25.1318 27.0738L27.4117 24.7984L29.1999 23.0102L37.6935 31.5039C38.0497 31.8627 38.3315 32.2884 38.5227 32.7565C38.7138 33.2246 38.8105 33.7259 38.8071 34.2315C38.8038 34.7371 38.7006 35.2371 38.5033 35.7027C38.306 36.1682 38.0187 36.5902 37.6577 36.9443Z\" fill=\"#3A6EF2\"><\/path><path d=\"M28.7082 27.2787C28.6362 27.2053 28.5503 27.147 28.4555 27.1072C28.3607 27.0674 28.2589 27.0469 28.1561 27.0469C28.0533 27.0469 27.9515 27.0674 27.8567 27.1072C27.7619 27.147 27.676 27.2053 27.604 27.2787C27.458 27.4253 27.376 27.6238 27.376 27.8308C27.376 28.0377 27.458 28.2362 27.604 28.3828L34.3095 35.0884C34.3823 35.1611 34.4687 35.2189 34.5639 35.2583C34.659 35.2977 34.7609 35.318 34.8639 35.318C34.9668 35.318 35.0687 35.2977 35.1639 35.2583C35.259 35.2189 35.3454 35.1611 35.4182 35.0884C35.491 35.0156 35.5487 34.9291 35.5881 34.834C35.6275 34.7389 35.6478 34.637 35.6478 34.534C35.6478 34.4311 35.6275 34.3291 35.5881 34.234C35.5487 34.1389 35.491 34.0525 35.4182 33.9797L28.7082 27.2787Z\" fill=\"#3A6EF2\"><\/path><\/svg>\t        <\/div>\n\t        \t        <div class=\"sasi-icon-box__content\">\n\t        \t<h4 class=\"icon-box-title\">Custom Services<\/h4>\t\t\t\t<div class=\"icon-box-des\">We offer custom services that designed specifically<\/div>\t\t\t\t\t\t\t<\/div>\t\n\t    <\/div>\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d21539 sasi-icon-align-left sasi-view-icon-default sasi-position-top elementor-widget elementor-widget-sasi-iconbox\" data-id=\"4d21539\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sasi-iconbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"sasi-icon-box\">\n\t\t\t\t\t\t<div class=\"sasi-icon sasi-icon-box__icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"41\" height=\"41\" viewBox=\"0 0 41 41\" fill=\"none\"><path d=\"M10.7202 34.3042C8.50561 35.5758 6.00929 36.0319 4.53109 36.1955C4.69474 34.7173 5.15081 32.221 6.4211 30.005C6.75376 29.4269 6.55389 28.6891 5.97576 28.3565C5.39226 28.0225 4.65852 28.225 4.3272 28.8032C2.05222 32.771 2.02539 37.3022 2.02539 37.494C2.02539 38.1606 2.56597 38.7012 3.23263 38.7012C3.42445 38.7012 7.95564 38.6744 11.9234 36.3994C12.5016 36.0667 12.7014 35.3303 12.3688 34.7508C12.0388 34.1727 11.3024 33.9715 10.7202 34.3042Z\" fill=\"#3A6EF2\"><\/path><path d=\"M40.3607 3.2942C40.3754 2.50144 40.0763 1.75832 39.5183 1.20164C38.9616 0.644971 38.1568 0.369988 37.4298 0.363281C34.087 0.426326 25.0703 1.38541 16.5391 9.04336C15.018 8.45181 12.7255 7.57321 10.9858 7.79722C8.4264 8.12586 4.64505 11.6081 0.941494 15.3237C0.450549 15.816 0.254707 16.5135 0.419697 17.1896C0.583345 17.8683 1.07966 18.4008 1.74498 18.6141L7.63365 20.5055C7.18965 21.3157 6.75236 22.1446 6.32982 23.0192C5.79864 24.1192 6.02399 25.4404 6.89052 26.3043L14.4197 33.8334C14.9723 34.3874 15.7128 34.6798 16.4599 34.6798C16.8825 34.6798 17.309 34.5873 17.7061 34.3955C18.5807 33.9729 19.4096 33.5356 20.2171 33.093L22.1098 38.9803C22.3231 39.6456 22.8556 40.142 23.5357 40.3069C23.6927 40.3445 23.851 40.3633 24.0092 40.3633C24.5257 40.3633 25.0233 40.1607 25.4016 39.7838C29.1172 36.0803 32.5994 32.3002 32.9267 29.7422C33.1534 27.9864 32.2721 25.7073 31.6806 24.1862C39.3372 15.655 40.2976 6.63826 40.3607 3.2942ZM3.14941 16.531C5.11453 14.5739 9.38281 10.4384 11.2929 10.1929C12.1447 10.0843 13.4821 10.488 14.6115 10.8972C12.6169 12.9589 10.6799 15.4297 8.87442 18.3686L3.14941 16.531ZM16.6558 32.2211C16.4854 32.3043 16.2668 32.2667 16.1273 32.1272L8.59676 24.5967C8.4586 24.4585 8.4197 24.2412 8.5042 24.0682C17.8818 4.64363 33.0501 2.86228 37.4767 2.77911H37.4874C37.6471 2.77911 37.7517 2.8502 37.8134 2.91191C37.8644 2.96288 37.9516 3.07555 37.9489 3.24993C37.863 7.67649 36.0803 22.8448 16.6558 32.2211ZM30.5324 29.4337C30.2869 31.3425 26.1514 35.6121 24.1943 37.5759L22.354 31.8522C25.2956 30.0467 27.7664 28.1084 29.8281 26.1138C30.2386 27.2419 30.6424 28.5766 30.5324 29.4337Z\" fill=\"#3A6EF2\"><\/path><path d=\"M31.2645 16.6257C33.239 14.6498 33.239 11.4359 31.2645 9.46C29.349 7.54719 26.0116 7.54719 24.0988 9.46C23.1424 10.4164 22.6152 11.6894 22.6152 13.0428C22.6152 14.3963 23.1437 15.6693 24.0988 16.6257C25.0552 17.5821 26.3282 18.1092 27.6816 18.1092C29.0351 18.1092 30.3067 17.5821 31.2645 16.6257ZM29.5555 14.9181C28.5535 15.9214 26.8057 15.9214 25.8064 14.9181C25.3047 14.4177 25.0284 13.7511 25.0284 13.0428C25.0284 12.3346 25.3047 11.6693 25.8064 11.1676C26.3067 10.6672 26.972 10.3909 27.6803 10.3909C28.3872 10.3909 29.0539 10.6672 29.5542 11.1676C30.5897 12.2018 30.5897 13.8839 29.5555 14.9181Z\" fill=\"#3A6EF2\"><\/path><\/svg>\t        <\/div>\n\t        \t        <div class=\"sasi-icon-box__content\">\n\t        \t<h4 class=\"icon-box-title\">Sustainability Quality<\/h4>\t\t\t\t<div class=\"icon-box-des\">commitment to sustainability means deliver solutions<\/div>\t\t\t\t\t\t\t<\/div>\t\n\t    <\/div>\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ffb2888 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"ffb2888\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-641627b elementor-widget elementor-widget-image\" data-id=\"641627b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"945\" height=\"774\" src=\"https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/about-image3.webp\" class=\"attachment-full size-full wp-image-913\" alt=\"\" srcset=\"https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/about-image3.webp 945w, https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/about-image3-300x246.webp 300w, https:\/\/sasico.pikathemes.site\/startup\/wp-content\/uploads\/sites\/5\/2025\/08\/about-image3-768x629.webp 768w\" sizes=\"(max-width: 945px) 100vw, 945px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef953d0 section-padd-bot e-flex e-con-boxed e-con e-parent\" data-id=\"ef953d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8461a7b animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"8461a7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Trusted by over 1.7 million companies worldwide<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f24ce5 animated-slow elementor-invisible elementor-widget elementor-widget-sasi-image-slider\" data-id=\"3f24ce5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"sasi-image-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"sasi-carousel sasi-image-carousel\" data-slider_options=\"{&quot;slides_show_desktop&quot;:6,&quot;slides_show_laptop&quot;:5,&quot;slides_show_tablet_extra&quot;:5,&quot;slides_show_tablet&quot;:4,&quot;slides_show_mobile_extra&quot;:4,&quot;slides_show_mobile&quot;:2,&quot;margin_desktop&quot;:70,&quot;margin_laptop&quot;:70,&quot;margin_tablet_extra&quot;:70,&quot;margin_tablet&quot;:70,&quot;margin_mobile_extra&quot;:70,&quot;margin_mobile&quot;:70,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_time_out&quot;:7000,&quot;loop&quot;:&quot;yes&quot;,&quot;arrows&quot;:false,&quot;dots&quot;:false,&quot;dots_style&quot;:null}\">\n\t\t\t<div class=\"owl-carousel owl-theme\">\n\n\t\t\t\t\t\t\t\t<a class=\"item_link\" href=\"#\" >\n\t\t\t\t\t\t<span class=\"item-image\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"148\" height=\"30\" viewBox=\"0 0 148 30\" fill=\"none\"><path d=\"M0 3.21H4.25339V25.56H16.0251V29.49H0V3.21ZM20.2186 3.21C21.6563 3.21 22.8844 4.32 22.8844 5.79C22.8844 7.26 21.6863 8.43 20.2186 8.43C18.7509 8.43 17.5527 7.26 17.5527 5.79C17.5527 4.35 18.7209 3.21 20.2186 3.21ZM18.1218 10.56H22.1955V29.52H18.1218V10.56ZM24.6217 10.56H28.6954V13.17C29.8935 11.16 31.9603 10.05 34.716 10.05C39.1492 10.05 41.9049 13.5 41.9049 18.96V29.49H37.8312V19.35C37.8312 15.81 36.2736 13.8 33.488 13.8C30.4028 13.8 28.7254 15.9 28.7254 19.68V29.49H24.6217V10.56ZM44.0615 3.21H48.1352V19.83L55.7434 10.56H60.8654L52.748 20.04L60.8654 29.49H55.7434L48.1352 20.25V29.49H44.0615V3.21ZM62.4829 5.73H66.6464V10.56H71.4989V13.95H66.6464V23.7C66.6464 24.93 67.3953 25.71 68.5934 25.71H71.3192V29.52H68.0542C64.5197 29.52 62.5128 27.42 62.5128 23.7L62.4829 5.73ZM73.5657 10.56H77.3398V12.9C78.3582 11.1 80.0356 10.05 82.1024 10.05C82.7314 10.05 83.0609 10.08 83.5402 10.23V14.01C83.2706 13.95 82.8512 13.86 82.0125 13.86C79.0172 13.86 77.3698 16.38 77.3698 20.7V29.46H73.2961V10.56H73.5657ZM93.0953 10.05C97.5883 10.05 102.471 12.75 102.471 20.46V21H87.8535C88.183 24.39 90.1299 26.25 93.4248 26.25C95.7911 26.25 97.7681 24.99 98.2174 23.22H102.381C101.932 27 97.9777 30 93.3949 30C87.524 30 83.8097 26.19 83.8097 20.01C83.8097 14.52 87.3742 10.05 93.0953 10.05ZM98.0975 17.64C97.5284 15.3 95.6713 13.83 93.0953 13.83C90.6092 13.83 88.8419 15.33 88.153 17.64H98.0975ZM113.554 10.05C118.047 10.05 122.929 12.75 122.929 20.46V21H108.312C108.641 24.39 110.588 26.25 113.883 26.25C116.249 26.25 118.226 24.99 118.676 23.22H122.809C122.39 27 118.436 30 113.853 30C107.982 30 104.268 26.19 104.268 20.01C104.268 14.52 107.832 10.05 113.554 10.05ZM118.556 17.64C117.987 15.3 116.13 13.83 113.524 13.83C111.037 13.83 109.27 15.33 108.581 17.64H118.556ZM123.917 9.99H131.196L126.014 5.07L128.86 2.16L133.802 7.2V0H138.085V7.2L143.028 2.16L145.873 5.07L140.691 9.99H147.97V14.07H140.631L145.873 19.11L143.028 21.96L135.929 14.85L128.83 21.96L125.984 19.11L131.196 14.04H123.858V9.99H123.917ZM133.832 19.86H138.115V29.52H133.832V19.86Z\" fill=\"#696969\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<a class=\"item_link\" href=\"#\" >\n\t\t\t\t\t\t<span class=\"item-image\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"200\" height=\"30\" viewBox=\"0 0 200 30\" fill=\"none\"><path d=\"M30.7868 15.1601C30.7868 23.3558 24.1122 29.9999 15.8785 29.9999C7.64477 29.9999 0.970703 23.3578 0.970703 15.1601C0.970703 6.96249 7.64527 0.320801 15.8785 0.320801C24.1117 0.320801 30.7868 6.96449 30.7868 15.1601Z\" fill=\"#696969\"><\/path><path d=\"M47.1407 15.1602C47.1407 22.8754 43.8032 29.1292 39.6866 29.1292C35.57 29.1292 32.2324 22.8734 32.2324 15.1602C32.2324 7.44699 35.57 1.19116 39.6866 1.19116C43.8032 1.19116 47.1407 7.44699 47.1407 15.1602Z\" fill=\"#696969\"><\/path><path d=\"M53.8314 15.1602C53.8314 22.0726 52.6574 27.6758 51.2096 27.6758C49.7618 27.6758 48.5879 22.0706 48.5879 15.1602C48.5879 8.24975 49.7618 2.64453 51.2101 2.64453C52.6584 2.64453 53.8314 8.24825 53.8314 15.1602Z\" fill=\"#696969\"><\/path><path d=\"M94.975 1.6075L95.0165 1.59849V1.28069H86.5383L78.666 19.5727L70.7937 1.28069H61.6573V1.59849L61.6983 1.6075C63.2459 1.95282 64.0315 2.4678 64.0315 4.32503V26.0678C64.0315 27.925 63.2428 28.44 61.6953 28.7853L61.6543 28.7943V29.1131H67.853V28.7953L67.812 28.7863C66.2645 28.441 65.4788 27.926 65.4788 26.0688V5.5862L75.5917 29.1131H76.1652L86.5727 4.93009V26.6058C86.4401 28.0726 85.6615 28.5256 84.2603 28.8384L84.2187 28.8479V29.1632H95.0165V28.8479L94.975 28.8384C93.5722 28.5256 92.7749 28.0726 92.6423 26.6058L92.6352 4.32503H92.6423C92.6423 2.4678 93.428 1.95282 94.975 1.6075ZM99.9071 16.0109C100.084 12.1043 101.503 9.28465 103.884 9.2361C104.619 9.24811 105.235 9.48634 105.714 9.94476C106.731 10.9212 107.209 12.9616 107.136 16.0109H99.9071ZM99.8003 17.1119H112.456V17.0594C112.42 14.0721 111.545 11.7484 109.857 10.153C108.398 8.77417 106.238 8.01547 103.969 8.01547H103.918C102.741 8.01547 101.297 8.29773 100.269 8.80921C99.0992 9.3447 98.0675 10.1454 97.209 11.1964C95.827 12.8895 94.9897 15.1776 94.7862 17.749C94.7796 17.8261 94.774 17.9032 94.7685 17.9802C94.7629 18.0573 94.7593 18.1264 94.7558 18.2C94.7487 18.3376 94.7431 18.4757 94.7401 18.6143C94.735 18.8365 94.7335 19.0603 94.7376 19.2855C94.8748 25.1094 98.0569 29.7637 103.709 29.7637C108.67 29.7637 111.559 26.1784 112.279 21.3659L111.915 21.2393C110.65 23.8257 108.377 25.3932 105.79 25.202C102.259 24.9407 99.5533 21.4009 99.7988 17.1129M126.765 25.0043C126.35 25.9777 125.484 26.5132 124.323 26.5132C123.162 26.5132 122.101 25.7255 121.347 24.2941C120.537 22.7577 120.111 20.5857 120.111 18.0128C120.111 12.6578 121.796 9.19406 124.403 9.19406C125.495 9.19406 126.355 9.72956 126.765 10.6639V25.0043ZM135.16 28.8218C133.613 28.46 132.827 27.921 132.827 25.9692V0L123.425 2.73855V3.07386L123.483 3.06936C124.779 2.96576 125.659 3.14293 126.17 3.60936C126.57 3.9747 126.765 4.53522 126.765 5.32396V8.88427C125.838 8.29923 124.735 8.01446 123.397 8.01446C120.684 8.01446 118.204 9.14402 116.416 11.1954C114.551 13.3334 113.566 16.2551 113.566 19.6438C113.565 25.6959 116.579 29.7637 121.064 29.7637C123.688 29.7637 125.798 28.3424 126.765 25.9452V29.1632H135.201V28.8299L135.16 28.8218ZM143.224 3.53179C143.224 1.64203 141.783 0.216702 139.871 0.216702C137.968 0.216702 136.479 1.67306 136.479 3.53179C136.479 5.39052 137.969 6.84688 139.871 6.84688C141.783 6.84688 143.224 5.42155 143.224 3.53179ZM145.443 28.8218C143.896 28.46 143.11 27.921 143.11 25.9692H143.103V8.07602L134.667 10.4708V10.7961L134.717 10.8006C136.543 10.9612 137.042 11.5828 137.042 13.6918V29.1632H145.486V28.8299L145.443 28.8218ZM167.061 28.8218C165.514 28.46 164.728 27.921 164.728 25.9692V8.07602L156.695 10.3917V10.718L156.743 10.723C158.235 10.8781 158.667 11.5352 158.667 13.6537V24.9643C158.169 25.9377 157.236 26.5157 156.105 26.5547C154.271 26.5547 153.261 25.3301 153.261 23.1065V8.07652L144.824 10.4713V10.7961L144.875 10.8006C146.7 10.9607 147.2 11.5823 147.2 13.6918V23.2642C147.196 23.9324 147.255 24.5996 147.376 25.257L147.528 25.9101C148.242 28.4405 150.113 29.7637 153.046 29.7637C155.529 29.7637 157.706 28.2438 158.665 25.8656V29.1687H167.101V28.8354L167.061 28.8218ZM199.836 29.1632V28.8293L199.795 28.8198C198.116 28.437 197.462 27.7153 197.462 26.2459V14.0746C197.462 10.2796 195.306 8.01446 191.694 8.01446C189.062 8.01446 186.842 9.51836 185.988 11.861C185.309 9.37874 183.355 8.01446 180.467 8.01446C177.929 8.01446 175.941 9.3382 175.088 11.5743V8.07752L166.651 10.3742V10.7015L166.702 10.706C168.506 10.8641 169.027 11.5037 169.027 13.5586V29.1632H176.899V28.8299L176.857 28.8198C175.518 28.5086 175.086 27.941 175.086 26.4847V12.5337C175.44 11.7154 176.154 10.746 177.566 10.746C179.32 10.746 180.208 11.9471 180.208 14.3133V29.1632H188.082V28.8299L188.041 28.8198C186.701 28.5086 186.269 27.941 186.269 26.4847V14.0731C186.272 13.609 186.235 13.1455 186.158 12.6878C186.533 11.7985 187.289 10.746 188.758 10.746C190.536 10.746 191.401 11.9126 191.401 14.3133V29.1632H199.836Z\" fill=\"#696969\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<a class=\"item_link\" href=\"#\" >\n\t\t\t\t\t\t<span class=\"item-image\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"153\" height=\"30\" viewBox=\"0 0 153 30\" fill=\"none\"><path d=\"M18.6027 5.63738L9.7867 11.2748L18.6027 16.9121L9.7867 22.5495L0.970703 16.8817L9.7867 11.2443L0.970703 5.63738L9.7867 0L18.6027 5.63738ZM9.7411 24.3626L18.5571 18.7252L27.3731 24.3626L18.5571 30L9.7411 24.3626ZM18.6027 16.8817L27.4187 11.2443L18.6027 5.63738L27.3731 0L36.1891 5.63738L27.3731 11.2748L36.1891 16.9121L27.3731 22.5495L18.6027 16.8817Z\" fill=\"#696969\"><\/path><path d=\"M43.1055 5.63743H50.2343C54.7791 5.63743 58.5335 8.27329 58.5335 14.2916V15.5562C58.5335 21.6202 55.0223 24.3474 50.3711 24.3474H43.1055V5.63743ZM47.0879 9.03509V20.9345H50.1431C52.7271 20.9345 54.4599 19.2433 54.4599 15.48V14.4896C54.4599 10.7263 52.6359 9.03509 50.0063 9.03509H47.0879ZM60.6463 9.21793H63.8383L64.3551 12.7375C64.9631 10.3454 66.5135 9.06557 69.3255 9.06557H70.3135V13.1031H68.6719C65.4343 13.1031 64.6439 14.2306 64.6439 17.4302V24.3931H60.7071V9.21793H60.6463ZM71.1039 17.1103V16.6836C71.1039 11.61 74.3415 8.83702 78.7495 8.83702C83.2487 8.83702 86.3951 11.61 86.3951 16.6836V17.1103C86.3951 22.0925 83.3399 24.774 78.7495 24.774C73.8703 24.7283 71.1039 22.1077 71.1039 17.1103ZM82.3671 17.0646V16.6836C82.3671 13.865 80.9535 12.1737 78.7039 12.1737C76.4999 12.1737 75.0407 13.7278 75.0407 16.6836V17.0646C75.0407 19.7918 76.4543 21.3459 78.7039 21.3459C80.9535 21.3002 82.3671 19.7918 82.3671 17.0646ZM88.4623 9.21793H91.7455L92.1255 12.0823C92.9159 10.1626 94.6031 8.83702 97.0959 8.83702C100.941 8.83702 103.48 11.61 103.48 16.7446V17.1712C103.48 22.1534 100.668 24.7893 97.0959 24.7893C94.7095 24.7893 93.0679 23.7075 92.2623 21.9706V29.6344H88.4167L88.4623 9.21793ZM99.4823 17.0646V16.7294C99.4823 13.7126 97.9319 12.2195 95.8647 12.2195C93.6607 12.2195 92.2015 13.9107 92.2015 16.7294V17.0188C92.2015 19.7004 93.6151 21.3916 95.8191 21.3916C98.0839 21.3459 99.4823 19.8985 99.4823 17.0646ZM109.301 21.5897L108.967 24.3627H105.593V4.14429H109.438V11.8995C110.289 9.91879 111.977 8.83702 114.363 8.83702C117.981 8.88273 120.656 11.3815 120.656 16.4094V16.8817C120.656 21.9097 118.117 24.7893 114.272 24.7893C111.733 24.7283 110.092 23.5552 109.301 21.5897ZM116.613 16.8817V16.5008C116.613 13.7278 115.108 12.1737 112.995 12.1737C110.837 12.1737 109.332 13.9107 109.332 16.5465V16.8817C109.332 19.7004 110.791 21.3459 112.949 21.3459C115.26 21.3459 116.613 19.8985 116.613 16.8817ZM122.343 17.1103V16.6836C122.343 11.61 125.581 8.83702 129.989 8.83702C134.488 8.83702 137.634 11.61 137.634 16.6836V17.1103C137.634 22.0925 134.533 24.774 129.989 24.774C125.109 24.7283 122.343 22.1077 122.343 17.1103ZM133.637 17.0646V16.6836C133.637 13.865 132.223 12.1737 129.973 12.1737C127.769 12.1737 126.31 13.7278 126.31 16.6836V17.0646C126.31 19.7918 127.724 21.3459 129.973 21.3459C132.238 21.3002 133.637 19.7918 133.637 17.0646ZM142.787 16.5008L137.482 9.21793H142.027L145.082 13.7735L148.183 9.21793H152.682L147.301 16.4551L152.971 24.3627H148.517L145.052 19.3347L141.677 24.3627H137.026L142.787 16.5008Z\" fill=\"#696969\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<a class=\"item_link\" href=\"#\" >\n\t\t\t\t\t\t<span class=\"item-image\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"108\" height=\"30\" viewBox=\"0 0 108 30\" fill=\"none\"><path d=\"M12.4754 4.96631V13.425H4.67265V4.96631H0.970703V25.1583H4.67366V16.9741H12.4744V25.1583H16.1784V4.96631H12.4754ZM28.0308 18.6319C28.0308 19.4412 27.708 20.2174 27.1334 20.7897C26.5587 21.362 25.7794 21.6835 24.9667 21.6835C24.1541 21.6835 23.3747 21.362 22.8001 20.7897C22.2255 20.2174 21.9027 19.4412 21.9027 18.6319V9.98262H18.3901V18.6319C18.3901 20.3673 19.0823 22.0317 20.3145 23.2588C21.5466 24.4859 23.2177 25.1753 24.9602 25.1753C26.7027 25.1753 28.3739 24.4859 29.606 23.2588C30.8381 22.0317 31.5303 20.3673 31.5303 18.6319V9.98262H28.0308V18.6319ZM54.0577 10.8739C54.0577 9.10032 55.2352 8.53841 56.525 8.53841C57.5653 8.53841 58.9382 9.32689 59.8371 10.283L62.1371 7.58226C60.9886 6.03524 58.6596 4.96631 56.7525 4.96631C52.9413 4.96631 50.1854 7.18902 50.1854 10.8739C50.1854 17.7107 58.5754 15.5409 58.5754 19.3675C58.5754 20.5472 57.4249 21.5892 56.1081 21.5892C54.0307 21.5892 53.3572 20.5782 52.4032 19.5082L49.8497 22.1521C51.4832 24.1483 53.4975 25.1623 55.9097 25.1623C59.5305 25.1623 62.4427 22.9126 62.4427 19.3954C62.4427 11.8061 54.0517 14.1645 54.0517 10.8739M105.963 21.9325C103.888 21.9325 103.297 21.0383 103.297 19.6689V13.6056H106.524V10.5336H103.297V6.48038L99.7358 8.07231V20.4225C99.7358 23.5814 101.925 25.1733 104.925 25.1733C105.396 25.1813 105.867 25.1433 106.33 25.0615L107.199 21.8756C106.807 21.9026 106.357 21.9295 105.963 21.9295M41.4015 10.0834C39.6618 10.0834 38.4472 10.5865 37.2727 11.7332V5.08708H33.7551V17.4063C33.7551 22.0174 37.1023 25.1773 40.8644 25.1773C45.0373 25.1773 48.7082 21.9615 48.7082 17.6318C48.7082 13.3561 45.33 10.0864 41.4015 10.0864M41.3795 21.6511C40.8552 21.6511 40.3361 21.5482 39.8518 21.3484C39.3674 21.1486 38.9274 20.8558 38.5567 20.4866C38.186 20.1174 37.8919 19.6791 37.6913 19.1967C37.4907 18.7144 37.3874 18.1974 37.3874 17.6753C37.3874 17.1531 37.4907 16.6361 37.6913 16.1538C37.8919 15.6714 38.186 15.2331 38.5567 14.8639C38.9274 14.4947 39.3674 14.2019 39.8518 14.0021C40.3361 13.8023 40.8552 13.6994 41.3795 13.6994C42.4383 13.6994 43.4537 14.1183 44.2023 14.8639C44.951 15.6095 45.3716 16.6208 45.3716 17.6753C45.3716 18.7297 44.951 19.741 44.2023 20.4866C43.4537 21.2322 42.4383 21.6511 41.3795 21.6511ZM79.6036 17.4482C79.6036 13.1106 75.9407 9.90277 71.7597 9.90277C67.9987 9.90277 64.6505 13.0617 64.6505 17.6738V30H68.168V23.3448C69.3405 24.4896 70.5572 24.9946 72.2949 24.9946C76.2233 24.9946 79.6036 21.7249 79.6036 17.4482ZM76.2724 17.4043C76.2724 18.4587 75.8518 19.47 75.1032 20.2156C74.3545 20.9612 73.3391 21.3801 72.2804 21.3801C71.2216 21.3801 70.2062 20.9612 69.4575 20.2156C68.7089 19.47 68.2883 18.4587 68.2883 17.4043C68.2883 16.3498 68.7089 15.3386 69.4575 14.593C70.2062 13.8473 71.2216 13.4285 72.2804 13.4285C73.3391 13.4285 74.3545 13.8473 75.1032 14.593C75.8518 15.3386 76.2724 16.3498 76.2724 17.4043Z\" fill=\"#696969\"><\/path><path d=\"M90.9699 9.7332V6.213C91.437 5.99559 91.8325 5.65053 92.1103 5.21798C92.3882 4.78543 92.5369 4.28319 92.5393 3.76972V3.68887C92.5393 2.19177 91.3207 0.97811 89.8174 0.97811H89.7363C89.0144 0.97811 88.3221 1.26371 87.8116 1.77207C87.3012 2.28044 87.0144 2.96993 87.0144 3.68887V3.76972C87.0168 4.28319 87.1656 4.78543 87.4434 5.21798C87.7212 5.65053 88.1167 5.99559 88.5838 6.213V9.7332C87.2414 9.93791 85.9771 10.4923 84.9189 11.3401L75.2251 3.82062C75.2943 3.5721 75.3303 3.31659 75.3343 3.06009C75.3355 2.45596 75.1568 1.86505 74.8207 1.36211C74.4847 0.859164 74.0064 0.466779 73.4464 0.234586C72.8864 0.00239329 72.2698 -0.0591757 71.6747 0.0576672C71.0795 0.17451 70.5325 0.464515 70.1029 0.891C69.6733 1.31748 69.3803 1.86129 69.261 2.45363C69.1418 3.04596 69.2016 3.66022 69.4329 4.2187C69.6642 4.77718 70.0566 5.2548 70.5605 5.59113C71.0644 5.92747 71.6571 6.10741 72.2637 6.1082C72.7944 6.10571 73.3152 5.96461 73.774 5.69899L83.3195 13.0967C82.462 14.3869 82.0146 15.9044 82.0357 17.4515C82.0568 18.9986 82.5454 20.5034 83.4377 21.77L80.5345 24.6624C80.2998 24.5876 80.0553 24.5479 79.809 24.5446C79.311 24.545 78.8244 24.6924 78.4106 24.9681C77.9967 25.2439 77.6742 25.6356 77.4839 26.0938C77.2935 26.5521 77.2438 27.0562 77.341 27.5426C77.4383 28.0289 77.6781 28.4756 78.0302 28.8263C78.3823 29.1769 78.8308 29.4158 79.3191 29.5126C79.8075 29.6095 80.3137 29.56 80.7738 29.3704C81.2339 29.1808 81.6272 28.8596 81.9041 28.4474C82.181 28.0353 82.329 27.5506 82.3294 27.0547C82.3261 26.8094 82.2863 26.5658 82.2111 26.3321L85.0833 23.4707C86.0199 24.1888 87.1091 24.6839 88.2675 24.918C89.4259 25.1521 90.6227 25.119 91.7663 24.8213C92.9099 24.5236 93.9698 23.9692 94.865 23.2005C95.7602 22.4318 96.4669 21.4692 96.9308 20.3865C97.3948 19.3038 97.6037 18.1296 97.5417 16.9541C97.4796 15.7785 97.1482 14.6327 96.5729 13.6044C95.9975 12.5761 95.1934 11.6926 94.2222 11.0216C93.2511 10.3506 92.1385 9.90985 90.9699 9.7332ZM89.7794 21.3108C89.2486 21.3254 88.7202 21.2338 88.2255 21.0416C87.7308 20.8493 87.2799 20.5602 86.8993 20.1915C86.5187 19.8227 86.2161 19.3817 86.0096 18.8945C85.803 18.4073 85.6965 17.8838 85.6965 17.355C85.6965 16.8261 85.803 16.3026 86.0096 15.8155C86.2161 15.3283 86.5187 14.8873 86.8993 14.5185C87.2799 14.1497 87.7308 13.8607 88.2255 13.6684C88.7202 13.4761 89.2486 13.3846 89.7794 13.3991C90.8082 13.435 91.7828 13.8671 92.4981 14.6045C93.2133 15.3418 93.6133 16.3268 93.6138 17.3521C93.6144 18.3773 93.2153 19.3627 92.5008 20.1008C91.7863 20.8388 90.8121 21.2719 89.7834 21.3088\" fill=\"#696969\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<a class=\"item_link\" href=\"#\" >\n\t\t\t\t\t\t<span class=\"item-image\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"91\" height=\"30\" viewBox=\"0 0 91 30\" fill=\"none\"><path d=\"M33.8755 29.5995C33.9203 29.689 33.8551 29.7944 33.755 29.7944H15.9752C7.65143 29.7944 0.96875 23.1874 0.96875 14.8972C0.96875 6.60699 7.65143 0 15.9752 0C24.2978 0 30.9805 6.60699 30.9805 14.8972C30.9805 16.946 30.5723 18.8918 29.8327 20.6604C29.7954 20.7494 29.7077 20.8069 29.6113 20.8069H22.8249C22.705 20.8069 22.6371 20.6683 22.712 20.5745C23.9384 19.0392 24.6661 17.0658 24.6661 14.8972C24.6661 9.93183 20.8532 5.99095 15.975 5.99095C11.0957 5.99095 7.28261 9.93183 7.28261 14.8972C7.28261 19.8626 11.4934 23.8035 16.3726 23.8035H30.7939C30.908 23.8035 31.0124 23.868 31.0635 23.9703L33.8755 29.5995Z\" fill=\"#696969\"><\/path><path d=\"M36.8773 19.9915H39.6713L41.0546 24.9134C41.1368 25.2242 41.2166 25.5352 41.2943 25.8457C41.3717 26.1565 41.4382 26.4401 41.4929 26.6957C41.5566 26.9975 41.6162 27.2853 41.6709 27.5595H41.6984C41.7532 27.2853 41.8126 26.9975 41.8765 26.6957C41.9314 26.4401 41.9929 26.1566 42.0613 25.8457C42.1299 25.5352 42.2096 25.2244 42.3009 24.9134L43.6842 19.9915H46.5194V29.7941H44.6704V24.1731C44.6704 23.972 44.6726 23.7549 44.6773 23.5217C44.6818 23.2887 44.6931 23.0673 44.7115 22.8568C44.7205 22.6194 44.7341 22.3817 44.7525 22.1441H44.7251C44.6794 22.3725 44.6337 22.5965 44.5882 22.8158C44.5424 23.0077 44.4944 23.2087 44.4443 23.419C44.3941 23.6295 44.3462 23.8257 44.3005 24.0085L42.6159 29.7941H40.712L39.0685 24.0085C39.0136 23.8257 38.9633 23.6295 38.9178 23.419C38.8721 23.2087 38.8265 23.0077 38.7808 22.8158C38.7351 22.5965 38.6894 22.3725 38.6438 22.1441H38.6163C38.6253 22.3819 38.639 22.6195 38.6575 22.8568C38.6665 23.0673 38.6757 23.2887 38.6849 23.5217C38.6939 23.755 38.6986 23.972 38.6986 24.1731V29.7941H36.877V19.9915H36.8773Z\" fill=\"#696969\"><\/path><path d=\"M50.9031 30C50.3187 30 49.8005 29.9041 49.3485 29.712C48.8965 29.5202 48.5153 29.2573 48.2048 28.9236C47.8943 28.5901 47.6592 28.1948 47.4995 27.7376C47.3395 27.2809 47.2598 26.7917 47.2598 26.2706C47.2598 25.7497 47.3442 25.2631 47.5132 24.8106C47.682 24.358 47.9193 23.9674 48.2255 23.6384C48.5313 23.3092 48.8965 23.0488 49.3211 22.8568C49.7457 22.6647 50.2136 22.5688 50.7249 22.5688C51.291 22.5688 51.7886 22.6715 52.2179 22.8773C52.647 23.0829 53.0075 23.3733 53.2998 23.7481C53.592 24.1229 53.8134 24.5685 53.9642 25.0849C54.1149 25.6014 54.1901 26.1748 54.1901 26.8054H49.095C49.1679 27.3539 49.3528 27.7834 49.6498 28.0942C49.9464 28.405 50.3597 28.5603 50.8893 28.5603C51.2543 28.5603 51.5466 28.4829 51.7659 28.3274C51.9849 28.1721 52.1446 27.962 52.2452 27.6967H54.0807C54.0166 28.0076 53.9001 28.3023 53.7313 28.5811C53.5623 28.86 53.343 29.1045 53.0739 29.3146C52.8045 29.5248 52.4871 29.6917 52.1221 29.8149C51.7567 29.9382 51.3504 30 50.9031 30ZM50.7523 24.0087C50.2593 24.0087 49.8847 24.1436 49.6293 24.4132C49.3735 24.6827 49.2047 25.0506 49.1226 25.5168H52.2454C52.218 25.0692 52.0695 24.7058 51.8003 24.4269C51.5308 24.1481 51.1816 24.0087 50.7523 24.0087Z\" fill=\"#696969\"><\/path><path d=\"M54.2305 22.7609H55.2028V20.5674H57.0244V22.7609H58.2297V23.9947H57.0244V27.7237C57.0244 27.989 57.0881 28.1718 57.2161 28.2722C57.3439 28.3729 57.5128 28.423 57.7228 28.423H58.0789C58.1426 28.423 58.2067 28.4185 58.2706 28.4091V29.7803C58.1791 29.7895 58.0789 29.794 57.9692 29.794C57.8686 29.803 57.7453 29.8077 57.5995 29.8077C57.4534 29.8077 57.289 29.8077 57.1065 29.8077C56.8781 29.8077 56.6522 29.7826 56.4286 29.7324C56.2047 29.6821 56.0017 29.5931 55.8192 29.4648C55.6365 29.3369 55.4881 29.1632 55.374 28.9439C55.2597 28.7246 55.2028 28.4504 55.2028 28.1212V23.9946H54.2305V22.7609Z\" fill=\"#696969\"><\/path><path d=\"M60.7083 23.8852H60.7493C60.9592 23.4832 61.1966 23.1814 61.4616 22.9803C61.7262 22.7794 62.0642 22.6787 62.475 22.6787C62.6667 22.6787 62.8127 22.6969 62.9133 22.7335V24.3648H62.8723C62.2604 24.301 61.7581 24.4335 61.3657 24.7625C60.9729 25.0917 60.7767 25.6263 60.7767 26.3666V29.7942H58.9141V22.7609H60.7083V23.8852Z\" fill=\"#696969\"><\/path><path d=\"M63.4473 19.9915H65.3099V21.6641H63.4473V19.9915ZM63.4473 22.7608H65.3099V29.7941H63.4473V22.7608Z\" fill=\"#696969\"><\/path><path d=\"M69.5025 30C68.9454 30 68.4456 29.9041 68.0028 29.712C67.5598 29.5202 67.1833 29.2573 66.8729 28.9236C66.5624 28.5901 66.3227 28.1969 66.1538 27.7445C65.9848 27.2921 65.9004 26.8054 65.9004 26.2843C65.9004 25.7634 65.9826 25.2768 66.147 24.8243C66.3113 24.3717 66.5462 23.9789 66.8522 23.6452C67.158 23.3117 67.5254 23.0488 67.9549 22.8568C68.384 22.6649 68.8679 22.5688 69.4066 22.5688C69.8631 22.5688 70.274 22.633 70.6393 22.7607C71.0043 22.8888 71.3218 23.0647 71.5911 23.2885C71.8604 23.5126 72.0794 23.7822 72.2485 24.0975C72.4173 24.413 72.5338 24.7623 72.5978 25.1463H70.7761C70.7122 24.8357 70.5683 24.5773 70.3446 24.3715C70.1209 24.1661 69.8355 24.0631 69.4885 24.0631C68.9222 24.0631 68.4976 24.2618 68.2148 24.6595C67.9317 25.0571 67.7902 25.5986 67.7902 26.284C67.7902 26.9513 67.9248 27.4885 68.1943 27.8949C68.4636 28.3016 68.8861 28.505 69.4612 28.505C69.8447 28.505 70.1597 28.4068 70.4062 28.2103C70.6526 28.0137 70.8079 27.7144 70.8718 27.3121H72.6661C72.6387 27.687 72.5449 28.0366 72.3853 28.3609C72.2252 28.6854 72.0107 28.969 71.7416 29.211C71.4721 29.4533 71.1478 29.6454 70.769 29.7868C70.3905 29.929 69.9682 30 69.5025 30Z\" fill=\"#696969\"><\/path><path d=\"M47.4151 16.9872L45.8153 15.2053C46.6946 14.1615 47.1124 12.7959 47.1124 11.4909C47.1124 8.86566 45.4089 5.99451 41.6841 5.99451C37.9594 5.99451 36.2559 8.86584 36.2559 11.4909C36.2559 14.1159 37.9446 16.9872 41.6841 16.9872C42.8055 16.9872 43.7412 16.7276 44.5036 16.2952L45.1326 16.9872H47.4151ZM41.6841 15.0663C39.5014 15.0663 38.364 13.2916 38.364 11.4907C38.364 9.6898 39.4816 8.00639 41.6841 8.00639C43.9768 8.00639 45.0042 9.68998 45.0042 11.4907C45.0042 12.2665 44.824 13.0372 44.4313 13.6635L43.7178 12.8687H41.3895L43.1331 14.7872C42.7245 14.9649 42.2439 15.0663 41.6841 15.0663Z\" fill=\"#696969\"><\/path><path d=\"M52.5494 16.3925V15.5698H52.5082C52.2706 15.8898 51.9992 16.1388 51.6932 16.3172C51.3872 16.4952 50.9878 16.5846 50.4947 16.5846C49.7092 16.5846 49.1068 16.3563 48.6866 15.899C48.2665 15.4421 48.0566 14.825 48.0566 14.048V9.35889H49.9058V13.7326C49.9058 14.1439 49.9994 14.4594 50.1866 14.6787C50.3736 14.898 50.6681 15.0077 51.0702 15.0077C51.5085 15.0077 51.853 14.8592 52.1043 14.5621C52.3554 14.2653 52.481 13.8834 52.481 13.4172V9.35889H54.3439V16.3925H52.5494Z\" fill=\"#696969\"><\/path><path d=\"M59.7002 16.3925C59.6455 16.3195 59.5996 16.2098 59.5632 16.0633C59.5267 15.9174 59.4993 15.7666 59.4809 15.6109H59.4536C59.3621 15.748 59.2594 15.8738 59.1454 15.988C59.0311 16.1024 58.8941 16.2004 58.7345 16.2828C58.5746 16.3651 58.3853 16.4314 58.166 16.4815C57.947 16.5318 57.6865 16.557 57.3854 16.557C56.6639 16.557 56.0748 16.3741 55.6185 16.0086C55.1618 15.6431 54.9336 15.1084 54.9336 14.4044C54.9336 14.0205 55.0065 13.6961 55.1528 13.4309C55.2986 13.1659 55.4997 12.9466 55.7555 12.7729C56.0111 12.5994 56.3102 12.4644 56.6528 12.3684C56.9951 12.2725 57.3627 12.197 57.7553 12.1421C58.3396 12.0599 58.7689 11.9731 59.0428 11.8815C59.3168 11.7902 59.4538 11.612 59.4538 11.3468C59.4538 11.0911 59.3555 10.8875 59.1593 10.7367C58.9629 10.5861 58.6684 10.5104 58.2758 10.5104C57.8375 10.5104 57.5089 10.5906 57.2896 10.7504C57.0706 10.9106 56.9471 11.1596 56.9197 11.4978H55.2625C55.2715 11.1871 55.3399 10.8924 55.4678 10.6134C55.5956 10.3347 55.7828 10.0902 56.0294 9.87976C56.276 9.66967 56.5864 9.50066 56.9609 9.37256C57.3352 9.24463 57.778 9.18066 58.2895 9.18066C59.3395 9.18066 60.0951 9.40697 60.5564 9.8594C61.0174 10.3118 61.2482 10.9493 61.2482 11.772V15.3505C61.2482 15.8808 61.3304 16.2053 61.4948 16.324V16.3925H59.7002ZM57.8374 15.2545C58.1021 15.2545 58.3374 15.2158 58.5428 15.1379C58.7482 15.0603 58.9217 14.9597 59.0633 14.8363C59.2048 14.7129 59.3121 14.5713 59.3852 14.4113C59.4581 14.2514 59.4948 14.0846 59.4948 13.9107V12.8551C59.3305 12.956 59.1319 13.0358 58.899 13.0951C58.6661 13.1549 58.431 13.2116 58.1936 13.2664C57.7006 13.3761 57.3352 13.5042 57.0979 13.6504C56.8603 13.7967 56.7417 14.0343 56.7417 14.3633C56.7417 14.6925 56.8421 14.9235 57.043 15.0559C57.2437 15.1884 57.5087 15.2545 57.8374 15.2545Z\" fill=\"#696969\"><\/path><path d=\"M63.972 10.3185H64.013C64.2504 9.93467 64.5358 9.64656 64.8691 9.45467C65.2025 9.26278 65.6109 9.16675 66.0951 9.16675C66.4601 9.16675 66.7913 9.23323 67.0881 9.36549C67.3848 9.4981 67.6382 9.6808 67.8483 9.91395C68.0584 10.1471 68.2227 10.4235 68.3415 10.7433C68.4601 11.0635 68.5195 11.4154 68.5195 11.799V16.3921H66.6567V12.0732C66.6567 11.6893 66.5516 11.3786 66.3417 11.1408C66.1316 10.9033 65.8303 10.7844 65.4377 10.7844C65.0268 10.7844 64.6864 10.933 64.4173 11.23C64.1478 11.5269 64.0132 11.9177 64.0132 12.4022V16.3921H62.1504V9.35882H63.9722V10.3185H63.972Z\" fill=\"#696969\"><\/path><path d=\"M68.8496 9.35884H69.8221V7.16516H71.6439V9.35884H72.8492V10.5929H71.6439V14.3221C71.6439 14.5873 71.7076 14.7702 71.8356 14.8705C71.9634 14.9712 72.1323 15.0213 72.3425 15.0213H72.6985C72.7623 15.0213 72.8263 15.0168 72.8902 15.0075V16.3786C72.7988 16.3878 72.6985 16.3923 72.5889 16.3923C72.4883 16.4013 72.365 16.406 72.2192 16.406C72.0729 16.406 71.9087 16.406 71.726 16.406C71.4976 16.406 71.2717 16.381 71.048 16.3307C70.824 16.2804 70.621 16.1914 70.4385 16.0631C70.2558 15.9352 70.1075 15.7615 69.9933 15.5422C69.879 15.323 69.8221 15.0487 69.8221 14.7195V10.5929H68.8496V9.35884Z\" fill=\"#696969\"><\/path><path d=\"M77.9713 16.3925V15.5698H77.9301C77.6925 15.8898 77.4211 16.1388 77.1151 16.3172C76.8091 16.4952 76.4096 16.5846 75.9166 16.5846C75.1311 16.5846 74.5286 16.3563 74.1085 15.899C73.6884 15.4421 73.4785 14.825 73.4785 14.048V9.35889H75.3278V13.7326C75.3278 14.1439 75.4214 14.4594 75.6086 14.6787C75.7957 14.898 76.0901 15.0077 76.4923 15.0077C76.9306 15.0077 77.2751 14.8592 77.5264 14.5621C77.7775 14.2653 77.9031 13.8834 77.9031 13.4172V9.35889H79.7659V16.3925H77.9713Z\" fill=\"#696969\"><\/path><path d=\"M80.6974 9.35882H82.4919V10.3048H82.5329C82.7246 9.98494 82.9894 9.71539 83.3272 9.49594C83.6649 9.27666 84.0807 9.16675 84.5737 9.16675C85.021 9.16675 85.4138 9.27882 85.7517 9.50278C86.0893 9.72674 86.3451 10.026 86.5188 10.4008H86.5462C86.7834 10.0168 87.0824 9.71521 87.4433 9.49594C87.804 9.27666 88.2081 9.16675 88.6556 9.16675C89.3952 9.16675 89.9658 9.38837 90.3678 9.83161C90.7695 10.275 90.9704 10.8853 90.9704 11.662V16.3923H89.1076V11.9775C89.1076 11.5756 89.0138 11.2738 88.8268 11.0727C88.6396 10.8718 88.3725 10.7711 88.0256 10.7711C87.6328 10.7711 87.3247 10.9105 87.1009 11.1893C86.877 11.4682 86.7654 11.8404 86.7654 12.3065V16.3923H84.9024V11.9775C84.9024 11.5756 84.8086 11.2738 84.6216 11.0727C84.4342 10.8718 84.1673 10.7711 83.8203 10.7711C83.4367 10.7711 83.1307 10.9105 82.9024 11.1893C82.6742 11.4682 82.5601 11.8404 82.5601 12.3065V16.3923H80.6973L80.6974 9.35882Z\" fill=\"#696969\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<a class=\"item_link\" href=\"#\" >\n\t\t\t\t\t\t<span class=\"item-image\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"111\" height=\"30\" viewBox=\"0 0 111 30\" fill=\"none\"><path d=\"M14.2644 0C21.1837 0 27.7216 5.36101 27.7216 13.1588C27.7216 17.5451 25.6512 21.1191 22.7092 23.5018C23.5809 24.9097 24.6706 25.8845 25.9781 25.8845C27.5036 25.8845 28.1574 24.6931 28.2664 23.7184H30.2278C30.3367 25.018 29.6829 30 24.2347 30C20.8568 30 19.1133 28.0505 17.8058 25.8845C16.7161 26.1011 15.5175 26.3177 14.3189 26.3177C7.61756 26.3177 0.970703 20.9567 0.970703 13.1588C0.970703 5.36101 7.61756 0 14.2644 0ZM63.1351 5.90253C68.6923 5.90253 73.1599 9.80144 73.2144 15.5957C73.2144 21.7148 68.6923 25.722 63.1351 25.722C57.7414 25.722 53.0559 21.6606 53.0559 15.5957C53.0559 9.69314 57.6869 5.90253 63.1351 5.90253ZM99.8018 5.90253C104.705 5.90253 107.756 7.20217 107.756 12.0758V20.4152C107.756 21.7148 108.192 22.3646 109.282 22.3646C109.827 22.3646 110.262 22.148 110.48 22.0397L110.971 23.0144C110.535 23.7726 109.118 25.1805 106.503 25.1805C104.215 25.1805 102.798 24.0975 102.58 22.3646H102.471C101.382 24.3141 99.4204 25.6137 96.5873 25.6137C93.2094 25.6137 91.1391 23.8809 91.1391 20.7401C91.1391 14.5668 99.8018 16.2996 102.308 12.1841V11.2094C102.308 8.2852 101.109 7.63538 99.8018 7.63538C95.8791 7.63538 97.6225 12.1841 94.1356 12.1841C92.3922 12.1841 91.7384 11.2094 91.7384 10.0181C91.7384 7.74368 94.5715 5.90253 99.8018 5.90253ZM37.8008 6.33574V19.0072C37.8008 21.3899 38.9994 22.4729 40.7429 22.4729C42.1594 22.4729 43.6849 21.8231 44.4477 20.3069V9.80144C44.4477 8.71841 44.1208 8.2852 42.9222 8.2852H41.6146V6.33574H49.8959V20.2527C49.8959 21.5523 50.3318 22.2022 51.8573 22.2022H52.0752V24.2599L44.6656 25.4513V22.6895H44.5566C43.1401 24.4765 41.0698 25.5596 38.3456 25.5596C34.9677 25.5596 32.4615 23.8267 32.4615 19.1697V9.80144C32.4615 8.71841 32.0257 8.2852 30.8271 8.2852H29.6285V6.33574H37.8008ZM86.9984 6.01083C88.7419 6.01083 90.1584 6.98556 90.1584 8.93502C90.1584 10.343 89.5046 11.7509 87.5433 11.7509C85.9088 11.7509 85.5819 10.2347 84.1654 10.2347C82.9667 10.2347 81.9861 11.426 81.9861 13.1588V20.8484C81.9861 22.5812 82.4219 23.1227 84.3833 23.1227H85.4729V25.1805H73.7047V23.1769H74.4675C76.4288 23.1769 76.6468 22.6354 76.6468 20.9025V9.80144C76.6468 8.71841 76.102 8.2852 74.9033 8.2852H73.8137V6.33574H81.3323L81.6592 10.2347H81.8771C82.6398 7.41877 84.9281 6.01083 86.9984 6.01083ZM14.3189 2.11191C9.30651 2.11191 7.12722 5.84838 7.12722 13.1047C7.12722 20.361 9.30651 24.0975 14.3189 24.0975C15.2451 24.0975 16.0623 23.8809 16.7161 23.6643C15.7354 21.3899 14.4279 19.2238 11.9217 19.2238C11.4858 19.2238 11.05 19.3321 10.6141 19.5487L9.85134 18.0325C10.941 17.1119 12.412 16.4079 14.4279 16.4079C17.5878 16.4079 19.2223 17.9242 20.5299 19.8736C21.2926 18.2491 21.6195 15.9747 21.6195 13.1047C21.6195 5.84838 19.4402 2.11191 14.3189 2.11191ZM63.1351 7.74368C60.52 7.74368 58.9945 10.343 58.9945 15.5415C58.9945 20.8484 60.52 23.556 63.1351 23.556C65.9682 23.556 67.0579 20.8484 67.1668 15.5415C67.2758 10.3971 65.9682 7.74368 63.1351 7.74368ZM102.254 14.4585C100.51 16.3538 96.4784 16.6245 96.4784 20.0903C96.4784 21.8231 97.568 22.7978 98.9846 22.7978C101.382 22.7978 102.254 20.7401 102.254 18.4657V14.4585Z\" fill=\"#696969\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<a class=\"item_link\" href=\"#\" >\n\t\t\t\t\t\t<span class=\"item-image\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"144\" height=\"30\" viewBox=\"0 0 144 30\" fill=\"none\"><path d=\"M110.228 11.125H116.039L117.735 16.65C118.283 18.475 119.231 21.925 119.231 21.925C119.231 21.95 119.256 21.95 119.281 21.95L119.306 21.925C119.306 21.925 120.279 18.425 120.827 16.65L122.598 11.125H126.912L128.658 16.65C129.232 18.55 130.154 21.925 130.154 21.925C130.154 21.95 130.179 21.95 130.204 21.95L130.229 21.925C130.229 21.925 131.177 18.5 131.726 16.65L133.421 11.125H138.833L132.972 29.375H127.66L126.214 24.8C125.665 23 124.668 19.5 124.668 19.5C124.668 19.475 124.643 19.475 124.618 19.475L124.593 19.5C124.593 19.5 123.62 22.925 123.022 24.775L121.55 29.4H116.139L110.228 11.125ZM71.049 1.47498H76.9346V29.4H71.049V1.47498ZM81.2989 1.47498H87.1845V29.4H81.2989V1.47498ZM104.268 20.325C104.268 17.6 102.322 15.75 100.053 15.75C97.7088 15.75 95.7635 17.6 95.7635 20.325C95.7635 23.05 97.7088 24.9 100.053 24.9C102.322 24.9 104.268 23.05 104.268 20.325ZM90.1024 20.325C90.1024 14.775 94.5665 10.675 100.028 10.675C105.44 10.675 109.904 14.775 109.904 20.325C109.904 25.9 105.44 30 100.028 30C94.5914 30 90.1024 25.9 90.1024 20.325ZM36.9824 4.07498V9.44998H47.382C47.4318 9.44998 47.4568 9.49998 47.4318 9.52497L36.9824 27.325C36.733 27.8 36.6582 27.875 36.6582 28.35V29.4H56.9336V24.025H45.6861C45.6612 24.025 45.6362 24 45.6362 23.975C45.6362 23.95 45.6362 23.95 45.6362 23.95L56.2103 5.92498C56.2852 5.74998 56.3849 5.62498 56.3849 5.19998V4.07498H36.9824ZM60.6994 11.125H66.585V29.375H60.6994V11.125ZM63.6422 1.97498C65.4876 1.97498 66.984 3.44998 66.984 5.29998C66.984 7.14998 65.4627 8.62498 63.6422 8.62498C61.7967 8.62498 60.3003 7.14998 60.3003 5.29998C60.3003 3.44998 61.8216 1.97498 63.6422 1.97498Z\" fill=\"#696969\"><\/path><path d=\"M19.1018 7.95C19.2265 7.925 19.3013 7.975 19.3761 8.05C19.825 8.575 21.3213 10.375 21.7204 10.875C21.7702 10.95 21.7702 11.05 21.6954 11.1L21.6705 11.125C18.6778 13.5 15.9345 16.2 13.4905 19.15C13.4656 19.2 13.4905 19.2 13.5155 19.175C16.7575 17.775 24.339 15.55 27.7556 14.925V10.6L14.3883 0L0.996094 10.6V15.35C5.13596 12.875 14.7375 9.05 19.1018 7.95Z\" fill=\"#696969\"><\/path><path d=\"M8.203 26.2C8.10325 26.25 7.97855 26.225 7.92867 26.15L5.43478 23.175C5.35996 23.1 5.35996 23.05 5.45972 22.925C7.38002 20.1 11.3204 15.675 13.8392 13.8C13.8891 13.75 13.8891 13.725 13.8143 13.75C11.1707 14.6 3.73893 17.8 0.970703 19.375V29.5H27.7801V19.75C24.1141 20.375 13.1659 23.625 8.203 26.2Z\" fill=\"#696969\"><\/path><path d=\"M142.774 8.525C142.774 8 142.4 7.625 141.901 7.625H140.953V10.175H141.377V9.425H141.801L142.275 10.2H142.749L142.25 9.375C142.549 9.225 142.774 8.925 142.774 8.525ZM141.876 9.05H141.377V8H141.876C142.15 8 142.35 8.225 142.35 8.525C142.35 8.825 142.15 9.05 141.876 9.05Z\" fill=\"#696969\"><\/path><path d=\"M141.751 6.75C140.529 6.75 139.557 7.725 139.557 8.95C139.557 10.175 140.529 11.15 141.751 11.15C142.973 11.15 143.946 10.175 143.946 8.95C143.946 7.725 142.973 6.75 141.751 6.75ZM141.751 10.725C140.779 10.725 139.981 9.925 139.981 8.95C139.981 7.975 140.779 7.175 141.751 7.175C142.724 7.175 143.522 7.975 143.522 8.95C143.547 9.925 142.749 10.725 141.751 10.725Z\" fill=\"#696969\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t<a class=\"item_link\" href=\"#\" >\n\t\t\t\t\t\t<span class=\"item-image\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"160\" height=\"30\" viewBox=\"0 0 160 30\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M109.646 22.9975C108.634 22.9975 107.658 22.6356 106.935 21.9119C106.212 21.1881 105.742 20.1025 105.742 18.6187C105.742 17.135 106.212 16.0494 106.935 15.3256C107.658 14.6019 108.634 14.24 109.646 14.24C110.658 14.24 111.634 14.6019 112.357 15.3256C113.08 16.0494 113.55 17.135 113.55 18.6187C113.55 20.1025 113.08 21.1881 112.357 21.9119C111.634 22.6356 110.658 22.9975 109.646 22.9975ZM109.646 9.46313C104.44 9.46313 100.5 13.2991 100.5 18.6187C100.5 23.9022 104.44 27.7744 109.646 27.7744C114.851 27.7744 118.792 23.9022 118.792 18.6187C118.792 13.2991 114.851 9.46313 109.646 9.46313Z\" fill=\"#696969\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M66.3763 22.9975C65.3641 22.9975 64.3881 22.6356 63.6651 21.9119C62.9421 21.1881 62.4722 20.1025 62.4722 18.6187C62.4722 17.135 62.9421 16.0494 63.6651 15.3256C64.3881 14.6019 65.3641 14.24 66.3763 14.24C67.3885 14.24 68.3645 14.6019 69.0875 15.3256C69.8105 16.0494 70.2805 17.135 70.2805 18.6187C70.2805 20.1025 69.8105 21.1881 69.0875 21.9119C68.4007 22.6356 67.4247 22.9975 66.3763 22.9975ZM66.3763 9.46313C61.1708 9.46313 57.2305 13.2991 57.2305 18.6187C57.2305 23.9022 61.1708 27.7744 66.3763 27.7744C71.5819 27.7744 75.5222 23.9022 75.5222 18.6187C75.5222 13.2991 71.5819 9.46313 66.3763 9.46313Z\" fill=\"#696969\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M133.001 27.7744H138.207V17.3884C138.207 16.5199 138.46 15.7961 138.93 15.2533C139.399 14.7467 140.086 14.3848 140.99 14.3848C141.93 14.3848 142.581 14.7105 142.978 15.1809C143.376 15.6514 143.593 16.3752 143.593 17.2437V27.7382H148.762V17.3884C148.762 16.5561 149.015 15.7961 149.485 15.2895C149.955 14.7467 150.642 14.421 151.51 14.421C152.449 14.421 153.1 14.7467 153.498 15.2171C153.895 15.6876 154.112 16.4113 154.112 17.2799V27.7744H159.173V16.339C159.173 14.0229 158.414 12.3221 157.185 11.2002C155.992 10.1146 154.402 9.60797 152.775 9.60797C151.618 9.60797 150.57 9.78891 149.63 10.2594C148.835 10.6574 148.112 11.2726 147.497 12.0688C146.485 10.4403 144.677 9.57178 142.508 9.57178C140.918 9.57178 139.11 10.187 137.953 11.4174V10.0422H132.965V27.7744H133.001Z\" fill=\"#696969\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M131.048 10.0422V15.3256L130.65 15.2533C130.18 15.1447 129.747 15.1085 129.349 15.1085C128.264 15.1085 127.288 15.3618 126.565 16.0494C125.879 16.7008 125.373 17.7864 125.373 19.5235V27.7382H120.203V10.0783H125.228V11.743C126.457 10.2593 128.409 9.93359 129.638 9.93359C130.036 9.93359 130.397 9.96978 130.723 10.006L131.048 10.0422Z\" fill=\"#696969\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M37.8906 19.0531H42.9154L42.9877 19.1255C43.0239 19.1617 43.06 19.2341 43.06 19.2703C43.1685 20.3559 43.6023 21.1882 44.253 21.7673C44.9036 22.3101 45.7351 22.5634 46.6027 22.5634C47.651 22.5634 48.5186 22.1653 49.1331 21.4777C49.7115 20.7902 50.0369 19.8493 50.0369 18.7998V4.10742H55.4955V18.9446C55.4955 23.6852 51.8444 27.6659 46.6388 27.6659C44.0361 27.6659 41.8671 26.7974 40.3488 25.3137C38.8667 23.8662 37.9629 21.7673 37.9268 19.2341L37.8906 19.0531Z\" fill=\"#696969\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M99.7434 6.53203L100.033 6.60441V2.62371L99.8881 2.55133C99.6712 2.44277 99.3458 2.37039 98.9843 2.29802C98.5867 2.22564 98.1529 2.18945 97.6829 2.18945C95.9116 2.18945 93.8872 2.76846 92.8389 3.85411C91.7905 4.90357 91.2121 6.42347 91.2121 8.23288V9.06521H88.6094V13.5887H91.2121V27.7383H96.4538V13.6249H99.9965V9.1014H96.4538V8.34144C96.4538 7.50912 96.743 7.03867 97.1045 6.78535C97.466 6.49585 97.9721 6.38728 98.4421 6.38728C99.1651 6.38728 99.5627 6.49585 99.7434 6.53203Z\" fill=\"#696969\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M86.7998 23.4318L87.0528 23.3594V27.3763L86.9443 27.4487C86.7636 27.5573 86.4383 27.6296 86.0768 27.702C85.7153 27.7744 85.2815 27.8106 84.8838 27.8106C83.2209 27.8106 81.3412 27.2316 80.3651 26.1459C79.3891 25.0603 78.8468 23.5404 78.8468 21.731V13.6972H76.3887V9.13748H78.8468V4.25208H83.7632V9.17367H87.089V13.7334H83.7632V21.6586C83.7632 22.4909 84.0162 22.9614 84.3777 23.2147C84.7392 23.5042 85.2092 23.6128 85.6068 23.6128C86.2575 23.5766 86.619 23.468 86.7998 23.4318Z\" fill=\"#696969\"><\/path><path d=\"M8.75362 28.4258C9.33202 29.0048 8.93437 29.9818 8.10293 29.9818H2.82509C1.77675 29.9818 0.945312 29.1857 0.945312 28.1724V23.1061C0.945312 22.31 1.9575 21.9119 2.53589 22.4547L8.75362 28.4258Z\" fill=\"#696969\"><\/path><path d=\"M16.9588 28.86C15.4044 27.3401 15.4044 24.8431 16.9588 23.3232L22.562 17.7864C24.1164 16.2665 26.6469 16.2665 28.2013 17.7864C29.7557 19.3063 29.7557 21.8033 28.2013 23.3232L22.5981 28.86C21.0437 30.3799 18.5132 30.3799 16.9588 28.86Z\" fill=\"#696969\"><\/path><path d=\"M2.13848 14.9638C0.584048 13.4439 0.584048 10.9469 2.13848 9.42702L10.5613 1.13993C12.1158 -0.379976 14.6462 -0.379976 16.2007 1.13993C17.7551 2.65983 17.7551 5.15682 16.2007 6.67672L7.77782 14.9638C6.22338 16.5199 3.69291 16.5199 2.13848 14.9638Z\" fill=\"#696969\"><\/path><path d=\"M9.8377 21.6224C8.28327 20.1025 8.28327 17.6055 9.8377 16.0856L22.6347 3.4921C24.1891 1.9722 26.7196 1.9722 28.274 3.4921C29.8284 5.012 29.8284 7.50899 28.274 9.02889L15.477 21.6224C13.9226 23.1423 11.4283 23.1423 9.8377 21.6224Z\" fill=\"#696969\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t<\/div>\n\t    <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d8ab6cf section-padd-bot e-flex e-con-boxed e-con e-parent\" data-id=\"d8ab6cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b083e2c e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"b083e2c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;bounceIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68fcd7e elementor-widget__width-initial elementor-widget elementor-widget-sasi-heading\" data-id=\"68fcd7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sasi-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"sasi-heading\">\r\n\t        <span class=\"sasi-heading__sub\">Ready to Build Smarter<\/span>\t        <h2 class=\"sasi-heading__title\">Transform your idea into digital scalable product<\/h2>\t    <\/div>\r\n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32b1103 elementor-widget elementor-widget-sasi-button\" data-id=\"32b1103\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sasi-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n\t\t<a href=\"#\" class=\"sasi-btn sasi-btn-primary sasi-btn-icon sasi-btn-icon__right\">\n\t\t\t<span class=\"sasi-text\">Start 14th Days Free Trial<\/span> \n\t\t\t\t\t\t\t<span class=\"sasi-icon\">\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\"><path d=\"M6.84375 13.8125C6.96875 13.9688 7.21875 13.9688 7.375 13.8125L13.9062 7.28125C14.0625 7.125 14.0625 6.90625 13.9062 6.75L7.375 0.21875C7.21875 0.0625 6.96875 0.0625 6.84375 0.21875L6.21875 0.8125C6.0625 0.96875 6.0625 1.21875 6.21875 1.34375L11.0625 6.1875H0.375C0.1875 6.1875 0 6.375 0 6.5625V7.4375C0 7.65625 0.1875 7.8125 0.375 7.8125H11.0625L6.21875 12.6875C6.0625 12.8125 6.0625 13.0625 6.21875 13.2188L6.84375 13.8125Z\" fill=\"#0E0E0E\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t    \n\t    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Learn about us Fueling Ambition with Strategy &amp; Design Home Who we are We\u2019re a creative startup agency built for bold thinks and early visionaries. Our Mission Our Vision Our Goals Our mission is to empower startups with innovative design, smart strategy, and scalable solutions. We aim to bridge the gap between vision and execution\u2014helping [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-747","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sasico.pikathemes.site\/startup\/wp-json\/wp\/v2\/pages\/747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sasico.pikathemes.site\/startup\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sasico.pikathemes.site\/startup\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sasico.pikathemes.site\/startup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sasico.pikathemes.site\/startup\/wp-json\/wp\/v2\/comments?post=747"}],"version-history":[{"count":205,"href":"https:\/\/sasico.pikathemes.site\/startup\/wp-json\/wp\/v2\/pages\/747\/revisions"}],"predecessor-version":[{"id":1458,"href":"https:\/\/sasico.pikathemes.site\/startup\/wp-json\/wp\/v2\/pages\/747\/revisions\/1458"}],"wp:attachment":[{"href":"https:\/\/sasico.pikathemes.site\/startup\/wp-json\/wp\/v2\/media?parent=747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}